{"id":14097,"date":"2024-08-08T20:00:17","date_gmt":"2024-08-08T16:30:17","guid":{"rendered":"https:\/\/www.eghamat24.com\/blog\/?p=14097"},"modified":"2024-09-16T13:48:04","modified_gmt":"2024-09-16T10:18:04","slug":"environmental-protection","status":"publish","type":"post","link":"https:\/\/www.eghamat24.com\/blog\/14097\/environmental-protection","title":{"rendered":"\u06f2\u06f0+ \u0631\u0648\u0634 \u062d\u0641\u0627\u0638\u062a \u0627\u0632 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a \u0648 \u0627\u062d\u062a\u0631\u0627\u0645 \u0628\u0647 \u0637\u0628\u06cc\u0639\u062a \u062f\u0631 \u0633\u0641\u0631"},"content":{"rendered":"<p style=\"text-align: justify;\">\u0647\u0631 \u0633\u0627\u0644 \u0647\u0632\u0627\u0631\u0627\u0646\u200c\u0647\u0632\u0627\u0631 \u06af\u0648\u0646\u0647 \u06af\u06cc\u0627\u0647\u06cc \u0648 \u062c\u0627\u0646\u0648\u0631\u06cc \u0646\u0627\u0628\u0648\u062f \u0645\u06cc\u200c\u0634\u0648\u0646\u062f \u0648 \u062a\u0639\u062f\u0627\u062f \u0632\u06cc\u0627\u062f\u06cc \u0627\u0632 \u0645\u0648\u062c\u0648\u062f\u0627\u062a \u0622\u0628\u0632\u06cc \u062f\u0631 \u0627\u062b\u0631 \u0622\u0644\u0648\u062f\u06af\u06cc \u0622\u0628\u200c\u0647\u0627 \u0645\u06cc\u200c\u0645\u06cc\u0631\u0646\u062f! \u0627\u06cc\u0646 \u0622\u0645\u0627\u0631\u0647\u0627 \u0648\u0627\u0642\u0639\u0627 \u063a\u0645\u200c\u0627\u0646\u06af\u06cc\u0632 \u0627\u0633\u062a! \u0628\u0647 \u062e\u0635\u0648\u0635 \u0648\u0642\u062a\u06cc \u0645\u06cc\u200c\u0641\u0647\u0645\u06cc\u0645 \u06a9\u0647 \u0639\u0627\u0645\u0644 \u0627\u06cc\u0646 \u0647\u0645\u0647 \u0622\u0633\u06cc\u0628 \u0648 \u0646\u0627\u0628\u0648\u062f\u06cc \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a\u060c \u062e\u0648\u062f\u062e\u0648\u0627\u0647\u06cc \u0648 \u0641\u0639\u0627\u0644\u06cc\u062a\u200c\u0647\u0627\u06cc \u0645\u062e\u0631\u0628 \u0627\u0646\u0633\u0627\u0646 \u0627\u0633\u062a. \u0628\u0627 \u0648\u062c\u0648\u062f \u0627\u06cc\u0646 \u0622\u0645\u0627\u0631\u0647\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 <a href=\"https:\/\/www.eghamat24.com\/blog\/6442\/international-day-of-environment\" target=\"_blank\" rel=\"noopener\"><strong>\u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a \u0627\u06cc\u0631\u0627\u0646 \u0648 \u062d\u0641\u0627\u0638\u062a<\/strong><\/a> \u0627\u0632 \u0622\u0646\u00a0\u0628\u06cc\u0634 \u0627\u0632 \u0647\u0631 \u0686\u06cc\u0632\u06cc \u0627\u0647\u0645\u06cc\u062a \u067e\u06cc\u062f\u0627 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647 \u0627\u0632 <strong><a href=\"https:\/\/www.eghamat24.com\/blog\/\" target=\"_blank\" rel=\"noopener\">\u0645\u062c\u0644\u0647 \u06af\u0631\u062f\u0634\u06af\u0631\u06cc<\/a><\/strong> \u0627\u0642\u0627\u0645\u062a\u06f2\u06f4 \u0645\u06cc\u200c\u062e\u0648\u0627\u0647\u06cc\u0645 \u0628\u06cc\u200c\u062a\u0639\u0627\u0631\u0641 \u0627\u0632 \u0622\u0633\u06cc\u0628\u200c\u0647\u0627\u06cc \u0627\u0646\u0633\u0627\u0646 \u0628\u0647 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a \u062d\u0631\u0641 \u0628\u0632\u0646\u06cc\u0645 \u0648 \u0627\u0644\u0628\u062a\u0647 \u0631\u0627\u0647\u200c\u062d\u0644\u200c\u0647\u0627\u06cc\u06cc \u06a9\u0627\u0631\u0628\u0631\u062f\u06cc \u0628\u0631\u0627\u06cc \u062d\u0641\u0627\u0638\u062a \u0627\u0632 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a \u0627\u0631\u0627\u0626\u0647 \u062f\u0647\u06cc\u0645 \u062a\u0627 \u0622\u06cc\u0646\u062f\u06af\u0627\u0646 \u0645\u0627 \u0633\u0647\u0645 \u0628\u06cc\u0634\u062a\u0631\u06cc \u0627\u0632 \u0632\u0645\u06cc\u0646 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u0646\u062f. \u0628\u0647 \u0639\u0644\u0627\u0648\u0647 \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647 \u0628\u0627 \u0646\u0648\u0639\u06cc \u0627\u0632 \u0633\u0641\u0631\u06a9\u0631\u062f\u0646 \u0628\u0647 \u0646\u0627\u0645 \u0633\u0641\u0631 \u0633\u0628\u0632 \u0622\u0634\u0646\u0627 \u0645\u06cc\u200c\u0634\u0648\u06cc\u062f \u062a\u0627 \u06af\u0634\u062a\u200c\u0648\u06af\u0630\u0627\u0631 \u0634\u0645\u0627 \u062f\u0631 <a href=\"https:\/\/www.eghamat24.com\/blog\/31962\/iran-attractions\" target=\"_blank\" rel=\"noopener\"><strong><span style=\"color: #0000ff;\">\u062c\u0627\u0647\u0627\u06cc \u062f\u06cc\u062f\u0646\u06cc \u0627\u06cc\u0631\u0627\u0646<\/span><\/strong><\/a> \u0628\u0627 \u0622\u0633\u06cc\u0628 \u0628\u0647 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a \u0622\u0646\u200c\u0647\u0627 \u0647\u0645\u0631\u0627\u0647 \u0646\u0628\u0627\u0634\u062f.<\/p>\n<h2 style=\"text-align: justify;\"><b>\u0628\u0647 \u06a9\u06cc\u0633\u0647\u200c\u0647\u0627\u06cc \u067e\u0644\u0627\u0633\u062a\u06cc\u06a9\u06cc \u0646\u0647 \u0628\u06af\u0648\u06cc\u06cc\u0645!<\/b><\/h2>\n<p style=\"text-align: justify;\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-37870 size-full\" src=\"https:\/\/www.eghamat24.com\/blog\/wp-content\/uploads\/2019\/09\/New-Project-48.webp\" alt=\" \u0637\u0628\u06cc\u0639\u062a \u0648 \u062d\u0641\u0627\u0638\u062a \u0627\u0632 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a \u0628\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u06a9\u06cc\u0633\u0647\u200c\u0647\u0627\u06cc \u067e\u0627\u0631\u0686\u0647\u200c\u0627\u06cc\" width=\"882\" height=\"552\" title=\"\" srcset=\"https:\/\/www.eghamat24.com\/blog\/wp-content\/uploads\/2019\/09\/New-Project-48.webp 882w, https:\/\/www.eghamat24.com\/blog\/wp-content\/uploads\/2019\/09\/New-Project-48-300x188.webp 300w, https:\/\/www.eghamat24.com\/blog\/wp-content\/uploads\/2019\/09\/New-Project-48-768x481.webp 768w\" sizes=\"(max-width: 882px) 100vw, 882px\" \/><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u0627\u06cc\u0646 \u0628\u0627\u0631 \u06a9\u0647 \u062e\u0648\u0627\u0633\u062a\u06cc\u062f \u0627\u0632 \u0641\u0631\u0648\u0634\u0646\u062f\u0647\u200c \u06cc\u0627 \u06a9\u0633\u06cc \u062f\u0631\u062e\u0648\u0627\u0633\u062a \u06a9\u06cc\u0633\u0647 \u067e\u0644\u0627\u0633\u062a\u06cc\u06a9\u06cc \u06a9\u0646\u06cc\u062f\u060c \u0628\u0647 \u0627\u06cc\u0646 \u0645\u0648\u0636\u0648\u0639 \u0639\u062c\u06cc\u0628 \u0648 \u062a\u0631\u0633\u0646\u0627\u06a9 \u0641\u06a9\u0631 \u06a9\u0646\u06cc\u062f \u06a9\u0647 \u067e\u0644\u0627\u0633\u062a\u06cc\u06a9\u060c \u0627\u06cc\u0646 \u0634\u06cc \u0633\u0628\u06a9 \u0648 \u0628\u0647 \u0638\u0627\u0647\u0631 \u06a9\u0627\u0631\u0628\u0631\u062f\u06cc\u060c <strong>\u0642\u0627\u062a\u0644<\/strong> \u0645\u06cc\u0644\u06cc\u0648\u0646\u200c\u0647\u0627 \u067e\u0631\u0646\u062f\u0647 \u062f\u0631\u06cc\u0627\u06cc\u06cc \u0648 \u0635\u062f\u0647\u0627 \u0647\u0632\u0627\u0631 \u067e\u0633\u062a\u0627\u0646\u062f\u0627\u0631 \u0627\u0633\u062a. \u062c\u0627\u06cc\u06af\u0632\u06cc\u0646 \u0633\u0627\u0644\u0645\u200c\u062a\u0631 \u0648 \u0628\u0647\u062a\u0631 \u0628\u0631\u0627\u06cc \u0627\u06cc\u0646 \u0634\u06cc \u0642\u0627\u062a\u0644\u060c<\/span><span style=\"font-weight: 400;\"> \u06a9\u06cc\u0633\u0647\u200c\u0647\u0627\u06cc \u067e\u0627\u0631\u0686\u0647\u200c\u0627\u06cc \u0627\u0633\u062a. \u067e\u0633 \u0627\u06cc\u0646 \u0628\u0627\u0631 \u0628\u0647 \u062c\u0627\u06cc \u062f\u0631\u062e\u0648\u0627\u0633\u062a \u0641\u0648\u0631\u06cc \u067e\u0644\u0627\u0633\u062a\u06cc\u06a9\u060c \u0628\u0647 \u0622\u0646 \u0646\u0647 \u0628\u06af\u0648\u06cc\u06cc\u062f \u0648 \u0627\u0632 \u06a9\u06cc\u0633\u0647 \u067e\u0627\u0631\u0686\u0647\u200c\u0627\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u0647\u0646\u0648\u0632 \u062f\u0631\u0628\u0627\u0631\u0647 \u0645\u0636\u0631\u0628\u0648\u062f\u0646 \u06a9\u06cc\u0633\u0647 \u067e\u0644\u0627\u0633\u062a\u06cc\u06a9\u06cc \u0642\u0627\u0646\u0639 \u0646\u0634\u062f\u0647\u200c\u0627\u06cc\u062f\u061f \u0627\u06af\u0631 \u0628\u0644\u0647\u060c \u067e\u06cc\u0634\u0646\u0647\u0627\u062f \u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645 \u0645\u0642\u0627\u0644\u0647<\/span><strong> <a href=\"https:\/\/www.eghamat24.com\/blog\/13744\/plastic-waste-zero\" target=\"_blank\" rel=\"noopener\">\u0622\u0644\u0648\u062f\u06af\u06cc \u0628\u0627 \u0632\u0628\u0627\u0644\u0647 \u067e\u0644\u0627\u0633\u062a\u06cc\u06a9\u06cc<\/a><\/strong> <span style=\"font-weight: 400;\">\u0631\u0627 \u0628\u062e\u0648\u0627\u0646\u06cc\u062f.<\/span><\/p>\n<h2 style=\"text-align: justify;\"><b>\u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0638\u0631\u0648\u0641 \u062a\u062c\u0632\u06cc\u0647\u200c\u067e\u0630\u06cc\u0631 \u0648 \u0686\u0646\u062f\u0628\u0627\u0631\u0645\u0635\u0631\u0641<\/b><\/h2>\n<p style=\"text-align: justify;\"><img decoding=\"async\" class=\"aligncenter wp-image-37871 size-full\" src=\"https:\/\/www.eghamat24.com\/blog\/wp-content\/uploads\/2019\/09\/New-Project-49.webp\" alt=\"\u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0638\u0631\u0648\u0641 \u062a\u062c\u0632\u06cc\u0647 \u067e\u0630\u06cc\u0631 \u0628\u0631\u0627\u06cc \u062d\u0641\u0627\u0638\u062a \u0627\u0632 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a \" width=\"882\" height=\"552\" title=\"\" srcset=\"https:\/\/www.eghamat24.com\/blog\/wp-content\/uploads\/2019\/09\/New-Project-49.webp 882w, https:\/\/www.eghamat24.com\/blog\/wp-content\/uploads\/2019\/09\/New-Project-49-300x188.webp 300w, https:\/\/www.eghamat24.com\/blog\/wp-content\/uploads\/2019\/09\/New-Project-49-768x481.webp 768w\" sizes=\"(max-width: 882px) 100vw, 882px\" \/><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u0638\u0631\u0648\u0641 \u06cc\u06a9\u200c\u0628\u0627\u0631\u0645\u0635\u0631\u0641 \u0627\u0632 \u0646\u0638\u0631 \u0645\u0636\u0631\u0628\u0648\u062f\u0646 \u0686\u06cc\u0632\u06cc \u06a9\u0645 \u0627\u0632 \u067e\u0644\u0627\u0633\u062a\u06cc\u06a9 \u0646\u0645\u06cc\u200c\u0622\u0648\u0631\u0646\u062f \u0648 \u062a\u062c\u0632\u06cc\u0647 \u0637\u0648\u0644\u0627\u0646\u06cc\u200c\u0645\u062f\u062a \u0627\u06cc\u0646 \u0638\u0631\u0648\u0641 \u0628\u0627\u0639\u062b \u0645\u06cc\u200c\u0634\u0648\u062f \u062a\u0627 \u0628\u0627\u0642\u06cc\u200c\u0645\u0627\u0646\u062f\u0647 \u062a\u062c\u0632\u06cc\u0647\u200c\u0646\u0634\u062f\u0647 \u0622\u0646\u200c\u0647\u0627 \u0628\u0647 \u062d\u06cc\u0627\u062a \u0648\u062d\u0634 \u0622\u0633\u06cc\u0628 \u0648\u0627\u0631\u062f \u06a9\u0646\u062f. \u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646 \u0628\u0647 \u062c\u0627\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0638\u0631\u0648\u0641 \u06cc\u06a9\u200c\u0628\u0627\u0631\u0645\u0635\u0631\u0641 \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u0627\u0632 \u0638\u0631\u0648\u0641 \u062a\u062c\u0632\u06cc\u0647\u200c\u067e\u0630\u06cc\u0631 \u0648 \u0686\u0646\u062f\u0628\u0627\u0631\u0645\u0635\u0631\u0641 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f. \u062f\u0631 \u0642\u0633\u0645\u062a \u0632\u06cc\u0631 \u0628\u0627 \u0686\u0646\u062f \u0646\u0645\u0648\u0646\u0647 \u0638\u0631\u0648\u0641 \u0633\u0627\u0644\u0645 \u0622\u0634\u0646\u0627 \u0645\u06cc\u200c\u0634\u0648\u06cc\u062f:<\/span><\/p>\n<ul style=\"text-align: justify;\">\n<li><span style=\"font-weight: 400;\">\u00a0\u0627\u0632 \u0638\u0631\u0648\u0641 \u067e\u0644\u0627\u0633\u062a\u06cc\u06a9\u06cc \u0686\u0646\u062f\u0628\u0627\u0631\u0645\u0635\u0631\u0641 \u06cc\u0627 \u0638\u0631\u0648\u0641\u06cc \u0627\u0632 \u062c\u0646\u0633 \u0628\u0627\u0645\u0628\u0648\u06cc \u0645\u0642\u0627\u0648\u0645 \u0646\u0633\u0628\u062a \u0628\u0647 \u0622\u0633\u06cc\u0628\u060c \u06af\u0631\u0645\u0627 \u0648 \u0633\u0631\u0645\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u00a0\u0628\u0647 \u062c\u0627\u06cc \u0628\u0637\u0631\u06cc\u200c\u0647\u0627\u06cc \u0622\u0628 \u0645\u0639\u062f\u0646\u06cc \u0627\u0632 \u0642\u0645\u0642\u0645\u0647 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0628\u0631\u0627\u06cc \u063a\u0630\u0627\u062e\u0648\u0631\u062f\u0646 \u06cc\u0627 \u0646\u0648\u0634\u06cc\u062f\u0646 \u0645\u0627\u06cc\u0639\u0627\u062a \u062f\u0631 \u0641\u0636\u0627\u06cc \u0628\u06cc\u0631\u0648\u0646 \u0648 \u062d\u062a\u06cc \u06a9\u0627\u0641\u0647\u200c\u0647\u0627 \u0648 \u0631\u0633\u062a\u0648\u0631\u0627\u0646\u200c\u0647\u0627\u060c \u0628\u0647 \u062c\u0627\u06cc \u0638\u0631\u0648\u0641 \u06cc\u06a9\u0628\u0627\u0631 \u0645\u0635\u0631\u0641\u060c \u0627\u0632 \u0642\u0627\u0634\u0642 \u0648 \u0686\u0646\u06af\u0627\u0644 \u0648 \u0644\u06cc\u0648\u0627\u0646 \u062e\u0627\u0646\u06af\u06cc \u062e\u0648\u062f \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0647\u0646\u06af\u0627\u0645 \u062e\u0631\u06cc\u062f \u0638\u0631\u0648\u0641 \u0686\u06a9 \u06a9\u0646\u06cc\u062f \u06a9\u0647 \u0639\u0644\u0627\u0645\u062a \u062a\u062c\u0632\u06cc\u0647\u200c\u067e\u0630\u06cc\u0631\u06cc \u0631\u0648\u06cc \u0622\u0646 \u062d\u06a9 \u0634\u062f\u0647 \u0628\u0627\u0634\u062f.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0628\u0631\u0627\u06cc \u062d\u0641\u0627\u0638\u062a \u0627\u0632 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a \u0627\u0632 \u0638\u0631\u0648\u0641\u06cc \u0627\u0632 \u062c\u0646\u0633 \u0646\u0634\u0627\u0633\u062a\u0647 \u0630\u0631\u062a\u060c \u0627\u0633\u062a\u06cc\u0644 \u0636\u062f \u0632\u0646\u06af \u0648 \u0646\u06cc\u0634\u06a9\u0631 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f.<\/span><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">\u0628\u06cc\u0631\u0648\u0646\u200c\u0627\u0646\u062f\u0627\u062e\u062a\u0646 \u0632\u0628\u0627\u0644\u0647 \u0645\u0645\u0646\u0648\u0639!<\/h2>\n<p style=\"text-align: justify;\"><img decoding=\"async\" class=\"aligncenter wp-image-38086 size-full\" src=\"https:\/\/www.eghamat24.com\/blog\/wp-content\/uploads\/2024\/08\/New-Project-2024-08-09T162434.260.webp\" alt=\"\u0631\u0647\u0627\u0646\u06a9\u0631\u062f\u0646 \u0632\u0628\u0627\u0644\u0647 \u062f\u0631 \u0637\u0628\u06cc\u0639\u062a \u06cc\u06a9\u06cc \u0627\u0632 \u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u062d\u0641\u0627\u0638\u062a \u0627\u0632 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a\" width=\"882\" height=\"552\" title=\"\" srcset=\"https:\/\/www.eghamat24.com\/blog\/wp-content\/uploads\/2024\/08\/New-Project-2024-08-09T162434.260.webp 882w, https:\/\/www.eghamat24.com\/blog\/wp-content\/uploads\/2024\/08\/New-Project-2024-08-09T162434.260-300x188.webp 300w, https:\/\/www.eghamat24.com\/blog\/wp-content\/uploads\/2024\/08\/New-Project-2024-08-09T162434.260-768x481.webp 768w\" sizes=\"(max-width: 882px) 100vw, 882px\" \/><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u0633\u0627\u0644\u0647\u0627\u0633\u062a \u06a9\u0647 \u0627\u0632 \u0647\u0645\u0647 \u0634\u0646\u06cc\u062f\u0647\u200c\u0627\u06cc\u0645 \u0632\u0628\u0627\u0644\u0647\u200c\u0647\u0627 \u0631\u0627 \u062f\u0631 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a \u0631\u0647\u0627 \u0646\u06a9\u0646\u06cc\u062f \u0627\u0645\u0627 \u06af\u0627\u0647\u06cc \u06cc\u0627 \u0628\u06cc\u0634\u062a\u0631 \u0627\u0648\u0642\u0627\u062a \u0627\u06cc\u0646 \u0645\u0648\u0636\u0648\u0639 \u0631\u0627 \u062c\u062f\u06cc \u0646\u0645\u06cc\u200c\u06af\u06cc\u0631\u06cc\u0645. \u06cc\u06a9\u06cc \u0627\u0632 \u0637\u0631\u0641\u062f\u0627\u0631\u0627\u0646 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a \u062d\u0631\u0641 \u062c\u0627\u0644\u0628\u06cc \u062f\u0631\u0627\u06cc\u0646\u200c\u0628\u0627\u0631\u0647 \u062f\u0627\u0631\u062f \u0648 \u0645\u06cc\u200c\u06af\u0648\u06cc\u062f: <strong>\u00ab\u0628\u0639\u0636\u06cc \u0627\u0632 \u0645\u0631\u062f\u0645 \u0641\u06a9\u0631 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f \u06a9\u0647 \u0632\u0628\u0627\u0644\u0647 \u0631\u0627 \u062f\u0648\u0631 \u0645\u06cc\u200c\u0627\u0646\u062f\u0627\u0632\u0646\u062f \u0627\u0645\u0627 \u062f\u0631\u0648\u0627\u0642\u0639 \u0628\u06cc\u0631\u0648\u0646\u06cc \u0648\u062c\u0648\u062f \u0646\u062f\u0627\u0631\u062f \u0648 \u0647\u0631 \u0686\u0647 \u0647\u0633\u062a \u06a9\u0631\u0647 \u0632\u0645\u06cc\u0646\u06cc \u0627\u0633\u062a \u06a9\u0647 \u062f\u0631\u0648\u0646 \u0622\u0646 \u0646\u0641\u0633 \u0645\u06cc\u200c\u06a9\u0634\u06cc\u0645 \u0648 \u0632\u0646\u062f\u06af\u06cc \u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645.\u00bb<\/strong> <\/span><span style=\"font-weight: 400;\">\u0628\u0639\u0636\u06cc \u0627\u0632 \u0627\u0641\u0631\u0627\u062f \u0632\u0628\u0627\u0644\u0647\u200c\u0647\u0627\u06cc\u06cc \u0645\u062b\u0644 \u0638\u0631\u0648\u0641 \u067e\u0644\u0627\u0633\u062a\u06cc\u06a9\u06cc \u062e\u0648\u062f \u0631\u0627 \u062f\u0631 \u0637\u0628\u06cc\u0639\u062a \u0631\u0647\u0627 \u0646\u0645\u06cc\u200c\u06a9\u0646\u0646\u062f \u0627\u0645\u0627 \u0632\u0628\u0627\u0644\u0647\u200c\u0647\u0627\u06cc \u062a\u0631 \u062e\u0648\u062f \u0631\u0627 \u0628\u06cc\u0631\u0648\u0646 \u0645\u06cc\u200c\u0627\u0646\u062f\u0627\u0632\u0646\u062f \u0686\u0648\u0646 \u0645\u0639\u062a\u0642\u062f\u0646\u062f \u06a9\u0647 \u0627\u06cc\u0646 \u062c\u0646\u0633 \u0632\u0628\u0627\u0644\u0647\u200c\u0647\u0627 \u062f\u0631 \u0637\u0628\u06cc\u0639\u062a \u062a\u062c\u0632\u06cc\u0647 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f. \u0628\u0644\u0647 \u062f\u0631\u0633\u062a \u0627\u0633\u062a \u06a9\u0647 \u0686\u0646\u06cc\u0646 \u0632\u0628\u0627\u0644\u0647\u200c\u0647\u0627\u06cc\u06cc \u062f\u0631 \u0637\u0628\u06cc\u0639\u062a \u062a\u062c\u0632\u06cc\u0647 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f \u0627\u0645\u0627 \u062a\u0627 \u0632\u0645\u0627\u0646\u06cc \u06a9\u0647 \u062a\u062c\u0632\u06cc\u0647 \u0634\u0648\u0646\u062f\u060c \u0622\u06cc\u0627 \u0638\u0627\u0647\u0631 \u0646\u0627\u062e\u0648\u0634\u0627\u06cc\u0646\u062f\u06cc \u0628\u0647 \u0637\u0628\u06cc\u0639\u062a \u0646\u0645\u06cc\u200c\u062f\u0647\u0646\u062f\u061f! \u062e\u0648\u0628 \u0627\u0633\u062a \u0647\u0645\u06cc\u0634\u0647 \u06a9\u06cc\u0633\u0647\u200c \u0632\u0628\u0627\u0644\u0647\u200c\u0627\u06cc \u0631\u0627 \u062f\u0631 \u0645\u0627\u0634\u06cc\u0646 \u06cc\u0627 \u0647\u0645\u0631\u0627\u0647 \u062e\u0648\u062f \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f \u062a\u0627 \u0645\u0628\u0627\u062f\u0627 \u0646\u0627\u0686\u0627\u0631 \u0646\u0634\u0648\u06cc\u062f \u0622\u0646 \u0631\u0627 \u0628\u06cc\u0631\u0648\u0646 \u0628\u06cc\u0646\u062f\u0627\u0632\u06cc\u062f.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u062d\u0627\u0644 \u06a9\u0647 \u0628\u0647 \u0627\u0647\u0645\u06cc\u062a \u0631\u0647\u0627\u0646\u06a9\u0631\u062f\u0646 \u0632\u0628\u0627\u0644\u0647 \u062f\u0631 \u0637\u0628\u06cc\u0639\u062a \u067e\u06cc \u0628\u0631\u062f\u06cc\u0645\u060c \u0627\u0632 \u0634\u0645\u0627 \u0645\u06cc\u200c\u062e\u0648\u0627\u0647\u06cc\u0645 \u0628\u0647 \u0642\u062f\u0631 \u062a\u0648\u0627\u0646 \u0648 \u0645\u06cc\u0644\u062a\u0627\u0646 \u0647\u0631 \u062c\u0627 \u06a9\u0647 \u0632\u0628\u0627\u0644\u0647\u200c\u0627\u06cc \u062f\u06cc\u062f\u06cc\u062f \u062c\u0645\u0639 \u06a9\u0646\u06cc\u062f \u0648 \u062f\u0631 \u0633\u0637\u0644 \u0632\u0628\u0627\u0644\u0647 \u0628\u06cc\u0646\u062f\u0627\u0632\u06cc\u062f. \u0645\u06cc\u200c\u062f\u0627\u0646\u06cc\u062f \u0641\u0627\u06cc\u062f\u0647 \u0627\u06cc\u0646 \u06a9\u0627\u0631 \u0686\u06cc\u0633\u062a\u061f \u0639\u0644\u0627\u0648\u0647 \u0628\u0631 \u0622\u0646\u06a9\u0647 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a \u0631\u0627 \u062a\u0645\u06cc\u0632 \u06a9\u0631\u062f\u0647\u200c\u0627\u06cc\u062f\u060c \u0628\u0647 \u062f\u06cc\u06af\u0631\u0627\u0646 \u0641\u0631\u0647\u0646\u06af \u067e\u0627\u06a9\u0633\u0627\u0632\u06cc \u0648 \u062a\u0645\u06cc\u0632 \u0646\u06af\u0647\u200c\u062f\u0627\u0634\u062a\u0646 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a \u0631\u0627 \u06cc\u0627\u062f\u0622\u0648\u0631\u06cc \u0645\u06cc\u200c\u06a9\u0646\u06cc\u062f.\u00a0<\/span><\/p>\n<h2 style=\"text-align: justify;\"><b>\u062a\u0641\u06a9\u06cc\u06a9 \u0632\u0628\u0627\u0644\u0647\u200c\u0647\u0627\u06cc \u062a\u0631 \u0648 \u062e\u0634\u06a9<\/b><span style=\"font-weight: 400;\">\u00a0<\/span><span style=\"font-weight: 400;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-38087 size-full\" src=\"https:\/\/www.eghamat24.com\/blog\/wp-content\/uploads\/2024\/08\/New-Project-2024-08-09T162944.200.webp\" alt=\"\u062a\u0641\u06a9\u06cc\u06a9 \u0632\u0628\u0627\u0644\u0647\u200c\u0647\u0627\u06cc \u062a\u0631 \u0648 \u062e\u0634\u06a9 \u06cc\u06a9\u06cc \u0627\u0632 \u0631\u0648\u0634\u200c\u0647\u0627\u06cc \u0645\u0648\u062b\u0631 \u062f\u0631 \u062d\u0641\u0627\u0638\u062a \u0627\u0632 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a\" width=\"882\" height=\"552\" title=\"\" srcset=\"https:\/\/www.eghamat24.com\/blog\/wp-content\/uploads\/2024\/08\/New-Project-2024-08-09T162944.200.webp 882w, https:\/\/www.eghamat24.com\/blog\/wp-content\/uploads\/2024\/08\/New-Project-2024-08-09T162944.200-300x188.webp 300w, https:\/\/www.eghamat24.com\/blog\/wp-content\/uploads\/2024\/08\/New-Project-2024-08-09T162944.200-768x481.webp 768w\" sizes=\"(max-width: 882px) 100vw, 882px\" \/><\/span><\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u0631\u0627\u0647 \u062f\u06cc\u06af\u0631 \u0628\u0631\u0627\u06cc \u0645\u0631\u0627\u0642\u0628\u062a \u0627\u0632 \u0637\u0628\u06cc\u0639\u062a \u0648 \u062d\u0641\u0627\u0638\u062a \u0627\u0632 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a<\/span><span style=\"font-weight: 400;\"> \u0627\u06cc\u0646 \u0627\u0633\u062a \u06a9\u0647 \u0632\u0628\u0627\u0644\u0647\u200c\u0647\u0627 \u0631\u0627 \u0627\u0632 \u06cc\u06a9\u062f\u06cc\u06af\u0631 \u062a\u0641\u06a9\u06cc\u06a9 \u06a9\u0646\u06cc\u062f. \u0627\u06af\u0631 \u062a\u0641\u06a9\u06cc\u06a9 \u0632\u0628\u0627\u0644\u0647 \u0628\u0631\u0627\u06cc\u062a\u0627\u0646 \u0633\u062e\u062a \u0627\u0633\u062a\u060c \u0622\u0646 \u0631\u0627 \u062f\u0631 \u0633\u0627\u062f\u0647\u200c\u062a\u0631\u06cc\u0646 \u062d\u0627\u0644\u062a \u0627\u062c\u0631\u0627 \u06a9\u0646\u06cc\u062f \u06cc\u0639\u0646\u06cc \u0641\u0642\u0637 \u0632\u0628\u0627\u0644\u0647\u200c\u0647\u0627\u06cc \u062e\u0634\u06a9 \u0648 \u062a\u0631 \u0631\u0627 \u062a\u0641\u06a9\u06cc\u06a9 \u06a9\u0646\u06cc\u062f. \u0645\u0646\u0638\u0648\u0631 \u0627\u0632 \u0632\u0628\u0627\u0644\u0647\u200c\u0647\u0627\u06cc \u062a\u0631 \u0632\u0628\u0627\u0644\u0647\u200c\u0647\u0627\u06cc\u06cc \u0645\u0627\u0646\u0646\u062f \u0628\u0627\u0642\u06cc\u200c\u0645\u0627\u0646\u062f\u0647 \u063a\u0630\u0627\u060c \u0645\u06cc\u0648\u0647 \u0648\u2026 \u0627\u0633\u062a \u0648 \u0632\u0628\u0627\u0644\u0647\u200c\u0647\u0627\u06cc \u062e\u0634\u06a9 \u0634\u0627\u0645\u0644 \u0628\u0637\u0631\u06cc \u067e\u0644\u0627\u0633\u062a\u06cc\u06a9\u06cc \u0648 \u0634\u06cc\u0634\u0647\u200c\u0627\u06cc\u060c \u0631\u0648\u0632\u0646\u0627\u0645\u0647 \u0648\u2026 \u0645\u06cc\u200c\u0634\u0648\u062f. \u0632\u0628\u0627\u0644\u0647\u200c\u0647\u0627\u06cc \u062e\u0634\u06a9 \u062e\u0648\u062f \u0628\u0647 \u062f\u0648 \u062f\u0633\u062a\u0647 \u0628\u0627\u0632\u06cc\u0627\u0641\u062a \u0648 \u063a\u06cc\u0631\u0642\u0627\u0628\u0644 \u0628\u0627\u0632\u06cc\u0627\u0641\u062a \u062a\u0642\u0633\u06cc\u0645 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f. \u0628\u0637\u0631\u06cc \u0648 \u06a9\u06cc\u0633\u0647\u060c \u06a9\u0627\u0631\u062f \u0648 \u0686\u0646\u06af\u0627\u0644 \u067e\u0644\u0627\u0633\u062a\u06cc\u06a9\u06cc \u0627\u0632 \u0632\u0628\u0627\u0644\u0647\u200c\u0647\u0627\u06cc \u0642\u0627\u0628\u0644 \u0628\u0627\u0632\u06cc\u0627\u0641\u062a \u0648 \u062f\u0633\u062a\u0645\u0627\u0644 \u06a9\u0627\u063a\u0630\u06cc \u0648 \u0628\u0639\u0636\u06cc \u0627\u0632 \u0648\u0633\u0627\u06cc\u0644 \u0641\u0648\u0645\u06cc \u0627\u0632 \u062c\u0645\u0644\u0647 \u0632\u0628\u0627\u0644\u0647\u200c\u0647\u0627\u06cc \u063a\u06cc\u0631\u0642\u0627\u0628\u0644 \u0628\u0627\u0632\u06cc\u0627\u0641\u062a \u0647\u0633\u062a\u0646\u062f. \u0628\u0631\u0627\u06cc \u0628\u0627\u0632\u06cc\u0627\u0641\u062a \u0632\u0628\u0627\u0644\u0647\u200c\u0647\u0627\u06cc \u0627\u0644\u06a9\u062a\u0631\u0648\u0646\u06cc\u06a9 \u0647\u0645 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0622\u0646\u200c\u0647\u0627 \u0631\u0627 \u0628\u0647 \u0633\u0627\u0645\u0627\u0646\u0647\u200c\u0647\u0627\u06cc \u0628\u0627\u0632\u06cc\u0627\u0641\u062a \u0632\u0628\u0627\u0644\u0647\u200c \u0628\u0633\u067e\u0627\u0631\u06cc\u062f.<\/span><\/p>\n<h2 style=\"text-align: justify;\"><b>\u0644\u0630\u062a\u200c\u0628\u0631\u062f\u0646 \u0627\u0632 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a \u0633\u0627\u0644\u0645\u200c\u062a\u0631 \u0628\u0627 \u0645\u0635\u0631\u0641 \u06a9\u0645\u200c\u062a\u0631<\/b><\/h2>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-37873 size-full\" src=\"https:\/\/www.eghamat24.com\/blog\/wp-content\/uploads\/2019\/09\/New-Project-51.webp\" alt=\"\u0635\u0631\u0641\u0647\u200c\u062c\u0648\u06cc\u06cc \u062f\u0631 \u0645\u0635\u0631\u0641 \u0628\u0631\u0627\u06cc \u062d\u0641\u0627\u0638\u062a \u0627\u0632 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a\" width=\"882\" height=\"552\" title=\"\" srcset=\"https:\/\/www.eghamat24.com\/blog\/wp-content\/uploads\/2019\/09\/New-Project-51.webp 882w, https:\/\/www.eghamat24.com\/blog\/wp-content\/uploads\/2019\/09\/New-Project-51-300x188.webp 300w, https:\/\/www.eghamat24.com\/blog\/wp-content\/uploads\/2019\/09\/New-Project-51-768x481.webp 768w\" sizes=\"(max-width: 882px) 100vw, 882px\" \/><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u0628\u0647 \u0637\u0648\u0631 \u06a9\u0644\u06cc \u06cc\u0627\u062f\u062a\u0627\u0646 \u0628\u0627\u0634\u062f \u06a9\u0647 \u0635\u0631\u0641\u0647\u200c\u062c\u0648\u06cc\u06cc \u062f\u0631 \u0645\u0635\u0631\u0641 \u0647\u0631 \u0686\u06cc\u0632\u06cc \u0627\u0632 \u0645\u0648\u0627\u062f\u063a\u0630\u0627\u06cc\u06cc \u0648 \u0644\u0628\u0627\u0633 \u06af\u0631\u0641\u062a\u0647 \u062a\u0627 \u0622\u0628 \u0648 \u0628\u0631\u0642\u060c \u06cc\u06a9\u06cc \u0627\u0632 \u0645\u0647\u0645\u200c\u062a\u0631\u06cc\u0646 \u0648 \u0628\u0647\u062a\u0631\u06cc\u0646 <\/span><span style=\"font-weight: 400;\">\u0631\u0627\u0647 \u0647\u0627\u06cc \u062d\u0641\u0638 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a \u0627\u0633\u062a. \u0627\u06af\u0631 \u0628\u0631\u0627\u06cc\u062a\u0627\u0646 \u0633\u0648\u0627\u0644 \u0627\u0633\u062a \u06a9\u0647 \u0645\u062b\u0644\u0627 \u0686\u06af\u0648\u0646\u0647 \u0644\u0628\u0627\u0633\u200c\u067e\u0648\u0634\u06cc\u062f\u0646 \u0645\u0646 \u0628\u0627\u0639\u062b \u0622\u0644\u0648\u062f\u06af\u06cc \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a \u0645\u06cc\u200c\u0634\u0648\u062f\u060c \u062e\u0648\u0628 \u0627\u0633\u062a \u0628\u062f\u0627\u0646\u06cc\u062f \u06a9\u0647 \u0645\u0635\u0631\u0641 \u0648 \u062a\u0648\u0644\u06cc\u062f \u0647\u0631 \u0686\u06cc\u0632\u06cc \u0628\u0627\u0639\u062b \u0627\u0646\u062a\u0634\u0627\u0631 \u0648 \u062a\u0648\u0644\u06cc\u062f \u06af\u0627\u0632\u0647\u0627\u06cc \u06af\u0644\u062e\u0627\u0646\u0647\u200c\u0627\u06cc \u062f\u0631 \u06a9\u0631\u0647 \u0632\u0645\u06cc\u0646 \u0645\u06cc\u200c\u0634\u0648\u062f. \u0646\u0645\u06cc\u200c\u062e\u0648\u0627\u0647\u06cc\u0645 \u0628\u062d\u062b \u0631\u0627 \u062e\u06cc\u0644\u06cc \u067e\u06cc\u0686\u06cc\u062f\u0647 \u0648 \u0633\u062e\u062a \u06a9\u0646\u06cc\u0645 \u0627\u0645\u0627 \u0647\u0645\u06cc\u0646 \u0627\u0646\u062a\u0634\u0627\u0631 \u06af\u0627\u0632\u0647\u0627\u06cc \u06af\u0644\u062e\u0627\u0646\u0647\u200c\u0627\u06cc \u0645\u0627\u0646\u0646\u062f \u062f\u06cc\u200c\u0627\u06a9\u0633\u06cc\u062f\u06a9\u0631\u0628\u0646 \u0628\u0627\u0639\u062b \u0627\u0641\u0632\u0627\u06cc\u0634 \u06af\u0631\u0645\u0627\u06cc\u0634 \u0632\u0645\u06cc\u0646 \u0648 \u062e\u06cc\u0644\u06cc \u0627\u0632 \u0622\u0633\u06cc\u0628\u200c\u0647\u0627\u06cc \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a\u06cc \u0645\u06cc\u200c\u0634\u0648\u062f. \u06cc\u06a9\u06cc \u0627\u0632<\/span><span style=\"font-weight: 400;\"> \u0631\u0627\u0647\u06a9\u0627\u0631\u0647\u0627\u06cc \u062e\u0644\u0627\u0642\u0627\u0646\u0647 \u0628\u0631\u0627\u06cc \u062d\u0641\u0627\u0638\u062a \u0627\u0632 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a <\/span><span style=\"font-weight: 400;\">\u0648 \u0645\u0635\u0631\u0641 \u06a9\u0645\u200c\u062a\u0631 \u062f\u0631 \u0647\u0631 \u0686\u06cc\u0632\u06cc\u060c <\/span><span style=\"font-weight: 400;\">\u0628\u0627\u0632\u0633\u0627\u0632\u06cc \u0648\u0633\u0627\u06cc\u0644 \u0642\u062f\u06cc\u0645\u06cc \u06cc\u0627 \u062e\u0631\u06cc\u062f \u0648\u0633\u0627\u06cc\u0644 \u062f\u0633\u062a \u062f\u0648\u0645 \u0627\u0633\u062a.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u00a0\u062f\u0631 \u0627\u062f\u0627\u0645\u0647 \u0645\u06cc\u200c\u06af\u0648\u06cc\u06cc\u0645 \u06a9\u0647 \u062f\u0631 \u0686\u0647 \u0645\u0648\u0627\u0631\u062f\u06cc \u0628\u06cc\u0634\u062a\u0631 \u0627\u0632 \u0647\u0631 \u0686\u06cc\u0632\u06cc \u0645\u0647\u0645 \u0627\u0633\u062a\u060c \u0635\u0631\u0641\u0647\u200c\u062c\u0648\u06cc\u06cc \u06a9\u0646\u06cc\u062f.<\/span><\/p>\n<h3 style=\"text-align: justify;\">\u062d\u0641\u0638 \u067e\u0627\u06a9\u06cc\u0632\u06af\u06cc \u0631\u0648\u062f\u062e\u0627\u0646\u0647\u200c\u0647\u0627 \u0648 \u0635\u0631\u0641\u0647 \u062c\u0648\u06cc\u06cc \u062f\u0631 \u0645\u0635\u0631\u0641 \u0622\u0628<\/h3>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-37876 size-full\" src=\"https:\/\/www.eghamat24.com\/blog\/wp-content\/uploads\/2019\/09\/New-Project-54.webp\" alt=\"\u0635\u0631\u0641\u0647 \u062c\u0648\u06cc\u06cc \u062f\u0631 \u0645\u0635\u0631\u0641 \u0622\u0628\" width=\"882\" height=\"552\" title=\"\" srcset=\"https:\/\/www.eghamat24.com\/blog\/wp-content\/uploads\/2019\/09\/New-Project-54.webp 882w, https:\/\/www.eghamat24.com\/blog\/wp-content\/uploads\/2019\/09\/New-Project-54-300x188.webp 300w, https:\/\/www.eghamat24.com\/blog\/wp-content\/uploads\/2019\/09\/New-Project-54-768x481.webp 768w\" sizes=\"(max-width: 882px) 100vw, 882px\" \/><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u062f\u0631 \u0647\u0631 \u062c\u0627\u06cc\u06cc \u0627\u0632 \u06a9\u0631\u0647 \u0632\u0645\u06cc\u0646 \u06a9\u0647 \u0632\u0646\u062f\u06af\u06cc \u06a9\u0646\u06cc\u062f \u0645\u0647\u0645 \u0627\u0633\u062a \u0628\u062f\u0627\u0646\u06cc\u062f \u06a9\u0647 <\/span><span style=\"font-weight: 400;\">\u0645\u0646\u0627\u0628\u0639 \u0622\u0628 \u0645\u062d\u062f\u0648\u062f \u0647\u0633\u062a\u0646\u062f \u0648 \u0628\u0627\u06cc\u062f \u062f\u0631 \u0645\u0635\u0631\u0641 \u0622\u0646 \u0635\u0631\u0641\u0647\u200c\u062c\u0648\u06cc\u06cc \u06a9\u0631\u062f. \u0628\u0627\u0632\u0646\u06af\u0630\u0627\u0634\u062a\u0646 \u0634\u06cc\u0631 \u0622\u0628\u060c \u062e\u0648\u062f\u062f\u0627\u0631\u06cc \u0627\u0632 \u0634\u0633\u062a\u0634\u0648\u06cc \u0628\u06cc\u0634 \u0627\u0632 \u062d\u062f\u060c \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0648\u0633\u0627\u06cc\u0644 \u06a9\u0627\u0647\u0634 \u0645\u0635\u0631\u0641 \u0622\u0628 \u0648\u2026 \u0627\u0632 \u0631\u0627\u0647\u200c\u0647\u0627\u06cc \u0633\u0627\u062f\u0647 \u0627\u0645\u0627 \u0645\u0648\u062b\u0631 \u0628\u0631\u0627\u06cc \u06a9\u0627\u0647\u0634 \u0645\u0635\u0631\u0641 \u0622\u0628 \u0647\u0633\u062a\u0646\u062f. \u0628\u0647 \u0639\u0644\u0627\u0648\u0647 \u0628\u0627\u06cc\u062f \u062d\u0648\u0627\u0633\u062a\u0627\u0646 \u0628\u0627\u0634\u062f \u06a9\u0647 \u06cc\u06a9 \u0631\u0627\u0647 \u062d\u0641\u0627\u0638\u062a \u0627\u0632 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a \u062f\u0631 \u0627\u0631\u062a\u0628\u0627\u0637 \u0628\u0627 \u0645\u0646\u0627\u0628\u0639 \u0622\u0628\u06cc\u060c \u062d\u0641\u0638 \u067e\u0627\u06a9\u06cc\u0632\u06af\u06cc \u0631\u0648\u062f\u062e\u0627\u0646\u0647\u200c\u0647\u0627\u0633\u062a. \u0628\u0647 \u0637\u0648\u0631 \u0645\u062b\u0627\u0644 \u062f\u0631 \u0622\u0628 \u0631\u0648\u062f\u062e\u0627\u0646\u0647\u200c\u0647\u0627 \u0646\u0628\u0627\u06cc\u062f \u0627\u0632 \u0645\u0648\u0627\u062f \u0634\u0648\u06cc\u0646\u062f\u0647 \u0628\u0631\u0627\u06cc \u0634\u0633\u062a\u200c\u0648\u0634\u0648 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u0628\u0631\u0627\u06cc \u0627\u06cc\u0646\u06a9\u0647 \u062f\u0642\u06cc\u0642\u200c\u062a\u0631 \u0628\u062f\u0627\u0646\u06cc\u062f\u060c \u0686\u0637\u0648\u0631 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u062f\u0631 \u0645\u0635\u0631\u0641 \u0622\u0628 \u0635\u0631\u0641\u0647\u200c\u062c\u0648\u06cc\u06cc \u06a9\u0631\u062f\u060c \u067e\u06cc\u0634\u0646\u0647\u0627\u062f \u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645 \u0645\u0642\u0627\u0644\u0647 <\/span><a href=\"https:\/\/www.eghamat24.com\/blog\/15403\/saving-water\" target=\"_blank\" rel=\"noopener\"><b>\u0627\u062d\u062a\u0631\u0627\u0645 \u0628\u0647 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a \u0628\u0627 \u0635\u0631\u0641\u0647 \u062c\u0648\u06cc\u06cc \u062f\u0631 \u0645\u0635\u0631\u0641 \u0622\u0628<\/b><\/a> <span style=\"font-weight: 400;\">\u0631\u0627 \u0645\u0637\u0627\u0644\u0639\u0647 \u06a9\u0646\u06cc\u062f.<\/span><\/p>\n<h3 style=\"text-align: justify;\"><b>\u06a9\u0627\u0647\u0634 \u0645\u0635\u0631\u0641 \u0645\u0648\u0627\u062f \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc<\/b><\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u0627\u06cc\u0646 \u0631\u0648\u0632\u0647\u0627 \u062a\u0642\u0631\u06cc\u0628\u0627 \u0627\u0632 \u0647\u0631 \u0686\u06cc\u0632\u06cc \u06a9\u0647 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645\u060c \u0628\u0647 \u0646\u0648\u0639\u06cc \u062f\u0631 \u0622\u0646 \u0645\u0648\u0627\u062f \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u0628\u0647 \u06a9\u0627\u0631 \u0631\u0641\u062a\u0647\u060c \u0627\u0632 \u0644\u0648\u0627\u0632\u0645 \u0622\u0631\u0627\u06cc\u0634\u06cc \u0648 \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u067e\u0644\u0627\u0633\u062a\u06cc\u06a9\u06cc \u06af\u0631\u0641\u062a\u0647 \u062a\u0627 \u062d\u062a\u06cc \u0645\u06cc\u0648\u0647\u200c\u0627\u06cc \u06a9\u0647 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0628\u0647 \u0633\u0645 \u0622\u0644\u0648\u062f\u0647 \u0628\u0627\u0634\u062f. \u0628\u06af\u0630\u0627\u0631\u06cc\u062f \u062d\u062c\u062a \u0631\u0627 \u0628\u0631 \u0634\u0645\u0627 \u062a\u0645\u0627\u0645 \u06a9\u0646\u06cc\u0645 \u0648 \u0628\u06af\u0648\u06cc\u06cc\u0645 \u0647\u0631\u06af\u0648\u0646\u0647 \u0645\u0648\u0627\u062f \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u0628\u0627\u0639\u062b \u0622\u0633\u06cc\u0628 \u0628\u0647 \u062e\u0627\u06a9 \u0648 \u0622\u0628 \u0648 \u0647\u0648\u0627\u06cc \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a\u0645\u0627\u0646 \u0645\u06cc\u200c\u0634\u0648\u062f\u060c \u067e\u0633 \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u062f\u0631 \u0645\u0635\u0631\u0641 \u0647\u0631 \u0686\u06cc\u0632\u06cc \u062f\u0642\u062a \u06a9\u0646\u06cc\u062f \u06a9\u0647 \u0645\u06cc\u0632\u0627\u0646 \u0645\u0648\u0627\u062f \u0634\u06cc\u0645\u06cc\u0627\u06cc\u06cc \u0622\u0646 \u0628\u0631\u0627\u06cc \u0633\u0644\u0627\u0645\u062a \u062e\u0648\u062f\u062a\u0627\u0646 \u0648 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a \u062f\u0631 \u06a9\u0645\u200c\u062a\u0631\u06cc\u0646 \u062d\u0627\u0644\u062a \u0645\u0645\u06a9\u0646 \u0628\u0627\u0634\u062f.<\/span><\/p>\n<h3 style=\"text-align: justify;\"><b>\u0635\u0631\u0641\u0647 \u062c\u0648\u06cc\u06cc \u062f\u0631 \u0645\u0635\u0631\u0641 \u0628\u0631\u0642<\/b><\/h3>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u0628\u0631\u0642\u06cc \u06a9\u0647 \u0647\u0631 \u0631\u0648\u0632 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645 \u0648 \u0641\u06a9\u0631 \u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645 \u0628\u0647 \u0631\u0627\u062d\u062a\u06cc \u062f\u0631\u062f\u0633\u062a\u0631\u0633 \u0627\u0633\u062a\u060c \u0628\u0647 \u0645\u0646\u0628\u0639\u06cc \u0628\u06cc\u200c\u0627\u0646\u062a\u0647\u0627 \u0648\u0635\u0644 \u0646\u06cc\u0633\u062a \u06a9\u0647 \u0628\u062a\u0648\u0627\u0646 \u0622\u0646 \u0631\u0627 \u0628\u06cc\u200c\u0645\u062d\u0627\u0628\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0631\u062f. \u0628\u0631\u0642 \u0645\u0648\u0631\u062f\u0646\u06cc\u0627\u0632 \u0645\u0627 \u062f\u0631 \u0627\u062b\u0631 \u0645\u0635\u0631\u0641 \u0627\u0646\u0648\u0627\u0639\u06cc \u0627\u0632 \u0627\u0646\u0631\u0698\u06cc \u062d\u0627\u0635\u0644 \u0645\u06cc\u200c\u0634\u0648\u062f\u060c \u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646 \u0647\u0631 \u0686\u0642\u062f\u0631 \u0628\u0631\u0642 \u06a9\u0645\u200c\u062a\u0631\u06cc \u0645\u0635\u0631\u0641 \u06a9\u0646\u06cc\u0645\u060c \u0645\u06cc\u0632\u0627\u0646 \u06a9\u0645\u200c\u062a\u0631\u06cc \u0627\u0632 \u0627\u0646\u0631\u0698\u06cc\u200c\u0647\u0627\u06cc \u0632\u0645\u06cc\u0646 \u0645\u0635\u0631\u0641 \u0645\u06cc\u200c\u0634\u0648\u062f \u0648 \u0647\u0645\u200c\u0686\u0646\u06cc\u0646 \u0633\u0648\u062e\u062a\u200c\u0647\u0627\u06cc \u0641\u0633\u06cc\u0644\u06cc \u06a9\u0645\u200c\u062a\u0631\u06cc \u0633\u0648\u0632\u0627\u0646\u062f\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f.\u00a0<\/span><\/p>\n<h2 style=\"text-align: justify;\"><b>\u0631\u0639\u0627\u06cc\u062a \u0633\u06a9\u0648\u062a \u0648 \u0622\u0631\u0627\u0645\u0634 \u062f\u0631 \u0637\u0628\u06cc\u0639\u062a<\/b><\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u0628\u0627 \u0627\u06cc\u0646 \u0635\u062d\u0646\u0647 \u0645\u0648\u0627\u062c\u0647 \u0634\u062f\u0647\u200c\u0627\u06cc\u062f \u06cc\u0627 \u06a9\u0644\u06cc\u067e\u06cc \u0631\u0627 \u062f\u06cc\u062f\u0647\u200c\u0627\u06cc\u062f \u06a9\u0647 \u0639\u062f\u0647\u200c\u0627\u06cc \u062f\u0631 \u0637\u0628\u06cc\u0639\u062a \u0628\u0627 \u062e\u0648\u062f\u0634\u0627\u0646 \u0628\u0627\u0646\u062f \u067e\u062e\u0634 \u0645\u0648\u0633\u06cc\u0642\u06cc \u0645\u06cc\u200c\u0628\u0631\u0646\u062f \u0648 \u0628\u0627 \u0635\u062f\u0627\u06cc \u0628\u0644\u0646\u062f \u0645\u0648\u0632\u06cc\u06a9 \u06af\u0648\u0634 \u0645\u06cc\u200c\u062f\u0647\u0646\u062f\u061f \u0639\u062c\u06cc\u0628 \u0627\u0633\u062a \u06a9\u0647 \u0686\u0646\u06cc\u0646 \u0627\u0641\u0631\u0627\u062f\u06cc \u0641\u0642\u0637 \u0628\u0647 \u0641\u06a9\u0631 \u062e\u0648\u0634\u200c\u06af\u0630\u0631\u0627\u0646\u06cc \u0644\u062d\u0638\u0647\u200c\u0627\u06cc \u062e\u0648\u062f \u0647\u0633\u062a\u0646\u062f \u0648 \u063a\u0627\u0641\u0644 \u0627\u0632 \u0627\u06cc\u0646 \u0645\u0627\u062c\u0631\u0627 \u06a9\u0647 \u062e\u06cc\u0644\u06cc \u0627\u0632 \u0645\u0648\u062c\u0648\u062f\u0627\u062a \u0632\u0646\u062f\u0647 <\/span><span style=\"font-weight: 400;\">\u062f\u0631 \u0627\u062b\u0631 \u0635\u062f\u0627\u0647\u0627\u06cc \u0628\u0644\u0646\u062f \u062f\u0686\u0627\u0631 \u0627\u0633\u062a\u0631\u0633 \u0648 \u062d\u062a\u06cc \u0645\u0631\u06af \u0645\u06cc\u200c\u0634\u0648\u0646\u062f \u06cc\u0627 \u0627\u0632 \u0645\u062d\u0644 \u0632\u0646\u062f\u06af\u06cc \u062e\u0648\u062f \u0641\u0631\u0627\u0631 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f. \u06cc\u06a9\u06cc \u0627\u0632 \u0622\u062f\u0627\u0628 \u0648 \u0627\u0635\u0648\u0644 \u062d\u0636\u0648\u0631 \u062f\u0631 \u0637\u0628\u06cc\u0639\u062a \u0627\u06cc\u0646 \u0627\u0633\u062a \u06a9\u0647 \u0628\u0647 \u062e\u0627\u0637\u0631 \u062d\u0641\u0638 \u0633\u0644\u0627\u0645\u062a \u0645\u0648\u062c\u0648\u062f\u0627\u062a \u0632\u0646\u062f\u0647\u060c \u062a\u0645\u0627\u0645 \u062a\u0644\u0627\u0634\u0645\u0627\u0646 \u0631\u0627 \u0628\u06a9\u0646\u06cc\u0645 \u062a\u0627 \u0622\u0644\u0648\u062f\u06af\u06cc \u0635\u0648\u062a\u06cc \u0628\u0631\u0627\u06cc \u0622\u0646\u200c\u0647\u0627 \u0627\u06cc\u062c\u0627\u062f \u0646\u0634\u0648\u062f.<\/span><\/p>\n<h2 style=\"text-align: justify;\"><b>\u0645\u0631\u0627\u0642\u0628\u062a \u0627\u0632 \u067e\u0648\u0634\u0634 \u06af\u06cc\u0627\u0647\u06cc<\/b><\/h2>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-37877 size-full\" src=\"https:\/\/www.eghamat24.com\/blog\/wp-content\/uploads\/2019\/09\/New-Project-55.webp\" alt=\"\u0645\u0631\u0627\u0642\u0628\u062a \u0627\u0632 \u067e\u0648\u0634\u0634 \u06af\u06cc\u0627\u0647\u06cc \u0648 \u0631\u0627\u0647 \u0647\u0627\u06cc \u062d\u0641\u0638 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a \" width=\"882\" height=\"552\" title=\"\" srcset=\"https:\/\/www.eghamat24.com\/blog\/wp-content\/uploads\/2019\/09\/New-Project-55.webp 882w, https:\/\/www.eghamat24.com\/blog\/wp-content\/uploads\/2019\/09\/New-Project-55-300x188.webp 300w, https:\/\/www.eghamat24.com\/blog\/wp-content\/uploads\/2019\/09\/New-Project-55-768x481.webp 768w\" sizes=\"(max-width: 882px) 100vw, 882px\" \/><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u06af\u06cc\u0627\u0647\u0627\u0646 \u0648 \u062f\u0631\u062e\u062a\u0627\u0646 \u0628\u0627 \u0646\u0642\u0634 \u0645\u0647\u0645\u06cc \u06a9\u0647 \u062f\u0631 \u062a\u0635\u0641\u06cc\u0647 \u0647\u0648\u0627 \u0648 \u06a9\u0627\u0647\u0634 \u062f\u06cc\u200c\u0627\u06a9\u0633\u06cc\u062f\u06a9\u0631\u0628\u0646 \u062f\u0627\u0631\u0646\u062f\u060c \u0631\u06cc\u0647\u200c\u0647\u0627\u06cc \u0632\u0645\u06cc\u0646 \u0628\u0647 \u062d\u0633\u0627\u0628 \u0645\u06cc\u200c\u0622\u06cc\u0646\u062f. \u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646 \u0628\u0627 \u0627\u06cc\u0646 \u0645\u0648\u062c\u0648\u062f\u0627\u062a \u0632\u0645\u06cc\u0646 \u0647\u0645\u0627\u0646\u0646\u062f \u06cc\u06a9 \u0639\u0636\u0648 \u062d\u06cc\u0627\u062a\u06cc \u062e\u0648\u062f \u0628\u0631\u062e\u0648\u0631\u062f \u06a9\u0646\u06cc\u062f \u0648 \u062d\u0648\u0627\u0633\u062a\u0627\u0646 \u0628\u0627\u0634\u062f \u062a\u0627 \u0645\u0628\u0627\u062f\u0627 \u062f\u0631 \u067e\u06cc\u0634 \u0686\u0634\u0645 \u0634\u0645\u0627 \u0628\u0648\u062a\u0647\u200c\u0627\u06cc \u06a9\u0646\u062f\u0647 \u0634\u0648\u062f\u060c \u0646\u0647\u0627\u0644\u06cc \u062e\u0645 \u0634\u0648\u062f \u0648 \u0634\u0627\u062e\u0647\u200c\u0627\u06cc \u0634\u06a9\u0633\u062a\u0647 \u0634\u0648\u062f.<\/span><\/p>\n<h2 style=\"text-align: justify;\">\u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0648\u0633\u0627\u06cc\u0644 \u062d\u0645\u0644\u200c\u0648\u0646\u0642\u0644 \u0639\u0645\u0648\u0645\u06cc<\/h2>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-37878 size-full\" src=\"https:\/\/www.eghamat24.com\/blog\/wp-content\/uploads\/2019\/09\/New-Project-56.webp\" alt=\"\u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0648\u0633\u0627\u06cc\u0644 \u062d\u0645\u0644 \u0648 \u0646\u0642\u0644 \u0639\u0645\u0648\u0645\u06cc \u0628\u0631\u0627\u06cc \u062d\u0641\u0627\u0638\u062a \u0627\u0632 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a\" width=\"882\" height=\"552\" title=\"\" srcset=\"https:\/\/www.eghamat24.com\/blog\/wp-content\/uploads\/2019\/09\/New-Project-56.webp 882w, https:\/\/www.eghamat24.com\/blog\/wp-content\/uploads\/2019\/09\/New-Project-56-300x188.webp 300w, https:\/\/www.eghamat24.com\/blog\/wp-content\/uploads\/2019\/09\/New-Project-56-768x481.webp 768w\" sizes=\"(max-width: 882px) 100vw, 882px\" \/><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u0645\u06cc\u200c\u062f\u0627\u0646\u06cc\u0645 \u0632\u0645\u0627\u0646\u06cc \u06a9\u0647 \u06a9\u0627\u0631 \u0648 \u0645\u0634\u063a\u0644\u0647 \u062f\u0627\u0631\u06cc\u062f\u060c \u0631\u0627\u062d\u062a\u200c\u062a\u0631\u06cc\u0646 \u06a9\u0627\u0631 \u0627\u06cc\u0646 \u0627\u0633\u062a \u06a9\u0647 \u0633\u0648\u0627\u0631 \u0645\u0627\u0634\u06cc\u0646 \u0634\u062e\u0635\u06cc \u062e\u0648\u062f \u0634\u062f\u0647 \u0648 \u0631\u0627\u0647\u06cc \u0645\u0642\u0635\u062f\u062a\u0627\u0646 \u0634\u0648\u06cc\u062f \u0627\u0645\u0627 \u0627\u06cc\u0646\u200c\u0628\u0627\u0631 \u0642\u0628\u0644 \u0627\u0632 \u0646\u0634\u0633\u062a\u0646 \u062f\u0631 \u0645\u0627\u0634\u06cc\u0646 \u06a9\u0645\u06cc \u062a\u0639\u0644\u0644 \u06a9\u0646\u06cc\u062f \u0648 \u0628\u0647 \u06af\u0632\u06cc\u0646\u0647\u200c\u0647\u0627\u06cc \u062f\u06cc\u06af\u0631 \u0631\u0641\u062a\u200c\u0648\u0622\u0645\u062f\u06cc \u0645\u062b\u0644 \u0645\u062a\u0631\u0648 \u0648 \u0627\u062a\u0648\u0628\u0648\u0633 \u0648\u2026 \u0641\u06a9\u0631 \u06a9\u0646\u06cc\u062f. \u0628\u0627\u0648\u0631 \u06a9\u0646\u06cc\u062f \u0622\u0646\u200c\u0642\u062f\u0631\u0647\u0627 \u0647\u0645 \u06a9\u0647 \u0628\u0639\u0636\u06cc\u200c\u0647\u0627 \u0627\u0632 \u0648\u0633\u0627\u06cc\u0644 \u062d\u0645\u0644\u200c\u0648\u0646\u0642\u0644 \u0639\u0645\u0648\u0645\u06cc \u0628\u062f\u06af\u0648\u06cc\u06cc \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f\u060c \u0628\u062f \u0646\u06cc\u0633\u062a\u0646\u062f \u0648 \u06af\u0627\u0647\u06cc \u062d\u062a\u06cc \u0633\u0631\u06cc\u0639\u200c\u062a\u0631 \u0648 \u0628\u0647\u200c\u0635\u0631\u0641\u0647\u200c\u062a\u0631 \u0627\u0632 \u0645\u0627\u0634\u06cc\u0646 \u0634\u062e\u0635\u06cc\u060c \u0634\u0645\u0627 \u0631\u0627 \u0628\u0647 \u0645\u0642\u0635\u062f \u0645\u06cc\u200c\u0631\u0633\u0627\u0646\u0646\u062f.<\/span><\/p>\n<h2 style=\"text-align: justify;\">\u0633\u0641\u0631 \u0633\u0628\u0632 \u0631\u0627 \u062a\u062c\u0631\u0628\u0647 \u06a9\u0646\u06cc\u062f<\/h2>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-37879 size-full\" src=\"https:\/\/www.eghamat24.com\/blog\/wp-content\/uploads\/2019\/09\/New-Project-57.webp\" alt=\"\u0633\u0641\u0631 \u0633\u0628\u0632\u061b \u0631\u0648\u0634\u06cc \u0628\u0631\u0627\u06cc \u0637\u0628\u06cc\u0639\u062a \u0648 \u062d\u0641\u0627\u0638\u062a \u0627\u0632 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a \" width=\"882\" height=\"552\" title=\"\" srcset=\"https:\/\/www.eghamat24.com\/blog\/wp-content\/uploads\/2019\/09\/New-Project-57.webp 882w, https:\/\/www.eghamat24.com\/blog\/wp-content\/uploads\/2019\/09\/New-Project-57-300x188.webp 300w, https:\/\/www.eghamat24.com\/blog\/wp-content\/uploads\/2019\/09\/New-Project-57-768x481.webp 768w\" sizes=\"(max-width: 882px) 100vw, 882px\" \/><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u062f\u0631\u0633\u062a \u0627\u0633\u062a \u06a9\u0647 \u062f\u0631 \u0645\u0648\u0627\u0642\u0639 \u0633\u0641\u0631\u06a9\u0631\u062f\u0646 \u062f\u0648\u0633\u062a \u062f\u0627\u0631\u06cc\u0645 \u0627\u0632 \u062e\u06cc\u0644\u06cc \u0627\u0632 \u06a9\u0627\u0631\u0647\u0627\u06cc \u0647\u0645\u06cc\u0634\u06af\u06cc \u0631\u0627\u062d\u062a \u0634\u0648\u06cc\u0645 \u0627\u0645\u0627 \u0628\u0627\u06cc\u062f \u0634\u0634\u200c\u062f\u0627\u0646\u06af \u062d\u0648\u0627\u0633\u0645\u0627\u0646 \u0631\u0627 \u062c\u0645\u0639 \u06a9\u0646\u06cc\u0645 \u06a9\u0647 \u0627\u06cc\u0646 \u0631\u0627\u062d\u062a\u06cc \u0628\u0647 \u0642\u06cc\u0645\u062a \u0627\u0632 \u062f\u0633\u062a\u200c\u0631\u0641\u062a\u0646 \u0633\u0644\u0627\u0645\u062a \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a \u0646\u0628\u0627\u0634\u062f. <\/span><b>\u0633\u0641\u0631 \u0633\u0628\u0632<\/b><span style=\"font-weight: 400;\"> \u0646\u0648\u0639\u06cc \u0627\u0632 \u0633\u0641\u0631 \u0627\u0633\u062a \u06a9\u0647 \u06af\u0631\u062f\u0634\u06af\u0631\u0627\u0646 \u0628\u0627 \u0631\u0639\u0627\u06cc\u062a \u06cc\u06a9\u0633\u0631\u06cc \u0627\u0632 \u0628\u0627\u06cc\u062f\u0647\u0627 \u0648 \u0646\u0628\u0627\u06cc\u062f\u0647\u0627\u060c \u0639\u0644\u0627\u0648\u0647 \u0628\u0631 \u0644\u0630\u062a\u200c\u0628\u0631\u062f\u0646 \u0627\u0632 \u0637\u0628\u06cc\u0639\u062a \u0648 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a \u0628\u0647 \u0633\u0644\u0627\u0645\u062a \u0622\u0646 \u0647\u0645 \u0627\u0647\u0645\u06cc\u062a \u0645\u06cc\u200c\u062f\u0647\u0646\u062f. \u062a\u0648\u0635\u06cc\u0647\u200c\u0647\u0627\u06cc \u0632\u06cc\u0631 \u0628\u0647 \u0634\u0645\u0627 \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f \u062a\u0627 \u0633\u0641\u0631\u06cc \u0633\u0628\u0632 \u0648 \u0628\u0647 \u062f\u0648\u0631 \u0627\u0632 \u0622\u0633\u06cc\u0628\u200c\u0647\u0627\u06cc \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a\u06cc \u0631\u0627 \u062a\u062c\u0631\u0628\u0647 \u06a9\u0646\u06cc\u062f.<\/span><\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0627\u06af\u0631 \u062d\u062a\u06cc \u0628\u0627 \u0645\u0627\u0634\u06cc\u0646 \u0634\u062e\u0635\u06cc \u062e\u0648\u062f \u0642\u0635\u062f \u0633\u0641\u0631 \u062f\u0627\u0631\u06cc\u062f\u060c \u0633\u0628\u06a9\u200c\u0628\u0627\u0631 \u0633\u0641\u0631 \u06a9\u0646\u06cc\u062f \u0686\u0631\u0627\u06a9\u0647 \u0628\u0627\u0639\u062b \u06a9\u0627\u0647\u0634 \u0645\u0635\u0631\u0641 \u0633\u0648\u062e\u062a \u062e\u0648\u062f\u0631\u0648 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0628\u0631\u0627\u06cc \u0627\u0642\u0627\u0645\u062a \u062e\u0648\u062f \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0633\u0631\u0627\u063a \u0627\u0642\u0627\u0645\u062a\u06af\u0627\u0647\u200c\u0647\u0627 \u0648 \u0647\u062a\u0644\u200c\u0647\u0627\u06cc \u0633\u0628\u0632 \u0628\u0631\u0648\u06cc\u062f. \u0627\u0645\u06a9\u0627\u0646\u0627\u062a \u0627\u06cc\u0646 \u0627\u0642\u0627\u0645\u062a\u06af\u0627\u0647\u200c\u0647\u0627 \u0637\u0648\u0631\u06cc \u0637\u0631\u0627\u062d\u06cc \u0634\u062f\u0647\u200c\u0627\u0646\u062f \u06a9\u0647 \u062d\u062f\u0627\u0642\u0644 \u0645\u06cc\u0632\u0627\u0646 \u0645\u0635\u0631\u0641 \u0627\u0646\u0631\u0698\u06cc \u0648 \u0622\u0633\u06cc\u0628 \u0628\u0647 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a \u0631\u0627 \u062f\u0627\u0631\u0646\u062f. \u0627\u06cc\u0646 \u0645\u062f\u0644 <\/span><span style=\"font-weight: 400;\">\u0647\u062a\u0644\u200c\u0647\u0627 \u062a\u0644\u0627\u0634 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f \u0627\u0632 \u0645\u0646\u0627\u0628\u0639 \u0627\u0646\u0631\u0698\u06cc \u062a\u062c\u062f\u06cc\u062f\u067e\u0630\u06cc\u0631 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0631\u062f\u0647 \u0648 \u062f\u0631 \u0645\u0635\u0631\u0641 \u0627\u0646\u0631\u0698\u06cc \u0635\u0631\u0641\u0647\u200c\u062c\u0648\u06cc\u06cc \u06a9\u0646\u0646\u062f.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0627\u06af\u0631 \u0628\u0627 \u0645\u0642\u0635\u062f \u0633\u0641\u0631 \u062e\u0648\u062f \u0641\u0627\u0635\u0644\u0647 \u0686\u0646\u062f\u0627\u0646 \u0632\u06cc\u0627\u062f\u06cc \u0646\u062f\u0627\u0631\u06cc\u062f \u0648 \u0627\u0647\u0644 \u0641\u0639\u0627\u0644\u06cc\u062a\u200c\u0647\u0627\u06cc \u0648\u0631\u0632\u0634\u06cc \u0647\u0633\u062a\u06cc\u062f\u060c \u0628\u0647 \u0633\u0641\u0631 \u0628\u0627 \u067e\u0627\u06cc \u067e\u06cc\u0627\u062f\u0647 \u06cc\u0627 \u062f\u0648\u0686\u0631\u062e\u0647 \u0641\u06a9\u0631 \u06a9\u0646\u06cc\u062f.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u062e\u06cc\u0644\u06cc \u062e\u0648\u0628 \u0627\u0633\u062a \u06a9\u0647 \u062f\u0631 \u0637\u0628\u06cc\u0639\u062a \u0622\u062a\u0634\u06cc \u0628\u0631\u067e\u0627 \u0646\u06a9\u0646\u06cc\u062f \u0648 \u0628\u0647 \u062c\u0627\u06cc \u0622\u0646 \u0627\u0632 \u06af\u0627\u0632\u0647\u0627\u06cc \u0645\u0633\u0627\u0641\u0631\u062a\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f. \u0627\u0645\u0627 \u0627\u06af\u0631 \u0627\u0635\u0631\u0627\u0631 \u0628\u0647 \u0627\u06cc\u0646 \u06a9\u0627\u0631 \u062f\u0627\u0631\u06cc\u062f\u060c \u062d\u0648\u0627\u0633\u062a\u0627\u0646 \u0628\u0627\u0634\u062f \u06a9\u0647 \u062d\u062a\u0645\u0627 \u0622\u062a\u0634 \u0631\u0627 \u0628\u0647 \u0637\u0648\u0631 \u06a9\u0627\u0645\u0644 \u062e\u0627\u0645\u0648\u0634 \u06a9\u0646\u06cc\u062f \u0648 \u0645\u0637\u0645\u0626\u0646 \u0634\u0648\u06cc\u062f \u06a9\u0647 \u062f\u0648\u062f \u0648 \u0622\u062a\u0634 \u0642\u0637\u0639 \u0634\u062f\u0647 \u0628\u0627\u0634\u062f \u0686\u0648\u0646 \u062d\u062a\u06cc \u0630\u0631\u0647\u200c\u0627\u06cc \u062e\u0627\u06a9\u0633\u062a\u0631 \u0634\u0639\u0644\u0647\u200c\u0648\u0631 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0627\u0639\u062b \u0622\u062a\u0634\u200c\u0633\u0648\u0632\u06cc \u06cc\u06a9 \u062c\u0646\u06af\u0644 \u0634\u0648\u062f. \u0628\u0631\u0627\u06cc \u062e\u0627\u0645\u0648\u0634\u200c\u06a9\u0631\u062f\u0646 \u0622\u062a\u0634 \u062e\u0648\u0628 \u0627\u0633\u062a \u06a9\u0647 \u0622\u0628 \u0631\u0627 \u0646\u0647 \u06cc\u06a9 \u062f\u0641\u0639\u0647 \u0628\u0644\u06a9\u0647 \u0645\u0631\u062d\u0644\u0647\u200c\u0627\u06cc \u0648 \u0628\u0647 \u062a\u062f\u0631\u06cc\u062c \u0628\u0631\u06cc\u0632\u06cc\u062f.<\/span><\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u0627\u06af\u0631 \u0632\u0645\u0627\u0646\u06cc \u0642\u0635\u062f \u0633\u0641\u0631 \u0628\u0647 \u0633\u0628\u06a9 \u06a9\u0645\u067e\u06cc\u0646\u06af \u0631\u0627 \u062f\u0627\u0634\u062a\u06cc\u062f \u0648 \u062e\u0648\u0627\u0633\u062a\u06cc\u062f \u0633\u0641\u0631\u06cc \u0628\u0647 \u062f\u0648\u0631 \u0627\u0632 \u0622\u0633\u06cc\u0628 \u0628\u0647 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a \u0631\u0627 \u062a\u062c\u0631\u0628\u0647 \u06a9\u0646\u06cc\u062f\u060c \u067e\u06cc\u0634\u0646\u0647\u0627\u062f \u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645 \u0645\u0642\u0627\u0644\u0647<\/span> <a href=\"https:\/\/www.eghamat24.com\/blog\/17815\/%DA%A9%D9%85%D9%BE%DB%8C%D9%86%DA%AF-%D8%AF%D8%B1-%D8%B7%D8%A8%DB%8C%D8%B9%D8%AA-%D8%AD%D9%81%D8%A7%D8%B8%D8%AA-%D9%85%D8%AD%DB%8C%D8%B7-%D8%B2%DB%8C%D8%B3%D8%AA\" target=\"_blank\" rel=\"noopener\"><b>\u06a9\u0645\u067e\u06cc\u0646\u06af \u062f\u0631 \u0637\u0628\u06cc\u0639\u062a \u0648 \u062a\u0648\u0635\u06cc\u0647\u200c\u0647\u0627\u06cc\u06cc \u0628\u0631\u0627\u06cc \u062d\u0641\u0627\u0638\u062a \u0627\u0632 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a<\/b><\/a><span style=\"font-weight: 400;\"> \u0631\u0627 \u0628\u062e\u0648\u0627\u0646\u06cc\u062f.<\/span><\/p>\n<h2 style=\"text-align: justify;\"><b>\u062f\u0641\u0646 \u067e\u0633\u0645\u0627\u0646\u062f\u0647\u0627\u06cc \u063a\u0630\u0627\u06cc\u06cc<\/b><\/h2>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-37881 size-full\" src=\"https:\/\/www.eghamat24.com\/blog\/wp-content\/uploads\/2019\/09\/New-Project-59.webp\" alt=\"\u062f\u0641\u0646 \u06a9\u0631\u062f\u0646 \u067e\u0633\u0645\u0627\u0646\u062f\u0647\u0627\u06cc \u063a\u0630\u0627 \u0628\u0631\u0627\u06cc \u062d\u0641\u0627\u0638\u062a \u0627\u0632 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a\" width=\"882\" height=\"552\" title=\"\" srcset=\"https:\/\/www.eghamat24.com\/blog\/wp-content\/uploads\/2019\/09\/New-Project-59.webp 882w, https:\/\/www.eghamat24.com\/blog\/wp-content\/uploads\/2019\/09\/New-Project-59-300x188.webp 300w, https:\/\/www.eghamat24.com\/blog\/wp-content\/uploads\/2019\/09\/New-Project-59-768x481.webp 768w\" sizes=\"(max-width: 882px) 100vw, 882px\" \/><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u0647\u0645\u0627\u0646\u200c\u0637\u0648\u0631 \u06a9\u0647 \u067e\u06cc\u0634\u062a\u0631 \u06af\u0641\u062a\u06cc\u0645\u060c \u0628\u0627 \u0648\u062c\u0648\u062f \u0622\u0646\u06a9\u0647 \u067e\u0633\u0645\u0627\u0646\u062f\u200c\u0647\u0627\u06cc \u063a\u0630\u0627\u06cc\u06cc \u062f\u0631 \u0637\u0628\u06cc\u0639\u062a \u062a\u062c\u0632\u06cc\u0647 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f \u0627\u0645\u0627 \u0646\u0628\u0627\u06cc\u062f \u0622\u0646\u200c\u0647\u0627 \u0631\u0627 \u062f\u0631 \u0637\u0628\u06cc\u0639\u062a \u0631\u0647\u0627 \u06a9\u0631\u062f. \u06cc\u06a9\u06cc \u0627\u0632 \u0631\u0627\u0647\u06a9\u0627\u0631\u0647\u0627\u06cc \u062e\u0644\u0627\u0642\u0627\u0646\u0647 \u0628\u0631\u0627\u06cc \u062d\u0641\u0627\u0638\u062a \u0627\u0632 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a \u0627\u06cc\u0646 \u0627\u0633\u062a \u06a9\u0647 \u0627\u06af\u0631 \u062f\u0631 \u062c\u0646\u06af\u0644 \u0648 \u06a9\u0648\u0647\u0633\u062a\u0627\u0646 \u0647\u0633\u062a\u06cc\u062f\u060c \u067e\u0633\u0645\u0627\u0646\u062f\u0647\u0627\u06cc \u063a\u0630\u0627\u06cc\u06cc<\/span><span style=\"font-weight: 400;\"> \u0645\u0627\u0646\u0646\u062f \u062a\u0641\u0627\u0644\u0647 \u0686\u0627\u06cc\u060c \u067e\u0648\u0633\u062a \u0645\u06cc\u0648\u0647\u200c\u0647\u0627\u060c \u062e\u0631\u062f\u0647\u200c\u0647\u0627\u06cc \u0646\u0627\u0646\u060c \u067e\u0648\u0633\u062a \u062a\u062e\u0645 \u0645\u0631\u063a \u0648\u2026 \u0631\u0627 \u062f\u0631\u0648\u0646 \u06cc\u06a9 \u06af\u0648\u062f\u0627\u0644 \u06a9\u0648\u0686\u06a9 \u062f\u0641\u0646 \u06a9\u0631\u062f\u0647 \u0648 \u0633\u067e\u0633 \u0622\u0646\u200c\u0647\u0627 \u0631\u0627 \u0628\u0627 \u0622\u0628 \u0645\u0631\u0637\u0648\u0628 \u06a9\u0646\u06cc\u062f. \u0628\u0639\u062f \u0627\u0632 \u0627\u06cc\u0646 \u0645\u0631\u0627\u062d\u0644\u060c \u062a\u0645\u0627\u0645 \u067e\u0633\u0645\u0627\u0646\u062f\u200c\u0647\u0627 \u0631\u0627 \u0628\u0627 \u062e\u0627\u06a9 \u0628\u067e\u0648\u0634\u0627\u0646\u06cc\u062f. \u0627\u06cc\u0646 \u06a9\u0627\u0631 \u0645\u06cc\u200c\u062f\u0627\u0646\u06cc\u062f \u0686\u0647 \u0641\u0627\u06cc\u062f\u0647\u200c\u0627\u06cc \u062f\u0627\u0631\u062f\u061f \u0628\u0627 \u062f\u0641\u0646 \u067e\u0633\u0645\u0627\u0646\u062f \u0628\u0647 \u062a\u062c\u0632\u06cc\u0647 \u0633\u0631\u06cc\u0639\u200c\u062a\u0631 \u0645\u0648\u0627\u062f \u063a\u0630\u0627\u06cc\u06cc \u06a9\u0645\u06a9 \u06a9\u0631\u062f\u0647\u200c\u0627\u06cc\u062f \u0648 \u0647\u0645\u200c\u0686\u0646\u06cc\u0646 \u0628\u0647 \u0638\u0627\u0647\u0631 \u0637\u0628\u06cc\u0639\u062a \u0628\u0627 \u067e\u0633\u0645\u0627\u0646\u062f\u200c\u0647\u0627\u06cc \u063a\u0630\u0627\u06cc\u06cc \u0622\u0644\u0648\u062f\u0647 \u0622\u0633\u06cc\u0628 \u0646\u0632\u062f\u0647\u200c\u0627\u06cc\u062f.<\/span><\/p>\n<h2 style=\"text-align: justify;\"><b>\u062a\u0648\u0644\u06cc\u062f \u06a9\u0645\u067e\u0648\u0633\u062a<\/b><\/h2>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-38088 size-full\" src=\"https:\/\/www.eghamat24.com\/blog\/wp-content\/uploads\/2024\/08\/New-Project-2024-08-09T163600.666.webp\" alt=\"\u062a\u0648\u0644\u06cc\u062f \u06a9\u0645\u067e\u0648\u0633\u062a \u0648 \u062d\u0641\u0627\u0638\u062a \u0627\u0632 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a\" width=\"882\" height=\"552\" title=\"\" srcset=\"https:\/\/www.eghamat24.com\/blog\/wp-content\/uploads\/2024\/08\/New-Project-2024-08-09T163600.666.webp 882w, https:\/\/www.eghamat24.com\/blog\/wp-content\/uploads\/2024\/08\/New-Project-2024-08-09T163600.666-300x188.webp 300w, https:\/\/www.eghamat24.com\/blog\/wp-content\/uploads\/2024\/08\/New-Project-2024-08-09T163600.666-768x481.webp 768w\" sizes=\"(max-width: 882px) 100vw, 882px\" \/><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u062a\u0648\u0644\u06cc\u062f \u06a9\u0645\u067e\u0648\u0633\u062a \u06cc\u06a9\u06cc \u062f\u06cc\u06af\u0631 \u0627\u0632 \u0631\u0627\u0647\u200c\u0647\u0627\u06cc \u062d\u0641\u0627\u0638\u062a \u0627\u0632 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a \u0627\u0633\u062a\u060c \u0628\u0647 \u0627\u06cc\u0646 \u062a\u0631\u062a\u06cc\u0628 \u06a9\u0647 \u06a9\u0648\u062f\u06cc \u0633\u0627\u0644\u0645 \u0648 \u0645\u063a\u0630\u06cc \u0628\u0631\u0627\u06cc \u062e\u0627\u06a9 \u06af\u06cc\u0627\u0647\u0627\u0646 \u0631\u0627 \u0627\u0632 \u067e\u0633\u0645\u0627\u0646\u062f\u0647\u0627\u06cc \u0622\u0644\u06cc \u062a\u062c\u0632\u06cc\u0647\u200c\u0634\u062f\u0647 \u062a\u0647\u06cc\u0647 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f. \u06a9\u0645\u067e\u0648\u0633\u062a \u062f\u0631\u0648\u0627\u0642\u0639 \u0641\u0631\u0627\u06cc\u0646\u062f \u067e\u0648\u0633\u0627\u0646\u062f\u0646 \u0648 \u062a\u062c\u0632\u06cc\u0647 \u0628\u0642\u0627\u06cc\u0627\u06cc \u06af\u06cc\u0627\u0647\u06cc \u0648 \u062d\u06cc\u0648\u0627\u0646\u06cc \u0648 \u0632\u0628\u0627\u0644\u0647\u200c\u0647\u0627\u06cc \u0634\u0647\u0631\u06cc \u0627\u0633\u062a.<\/span><\/p>\n<h2 style=\"text-align: justify;\"><b>\u062a\u0645\u0631\u06cc\u0646 \u06af\u06cc\u0627\u0647\u200c\u062e\u0648\u0627\u0631\u06cc \u06cc\u0627 \u06a9\u0645\u200c\u06a9\u0631\u062f\u0646 \u0645\u0635\u0631\u0641 \u06af\u0648\u0634\u062a<\/b><\/h2>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-38089 size-full\" src=\"https:\/\/www.eghamat24.com\/blog\/wp-content\/uploads\/2024\/08\/New-Project-2024-08-09T163956.201.webp\" alt=\"\u062a\u0645\u0631\u06cc\u0646 \u06af\u06cc\u0627\u0647\u200c\u062e\u0648\u0627\u0631\u06cc \u06cc\u06a9\u06cc \u0627\u0632 \u0631\u0627\u0647\u06a9\u0627\u0631\u0647\u0627\u06cc \u062e\u0644\u0627\u0642\u0627\u0646\u0647 \u062d\u0641\u0627\u0638\u062a \u0627\u0632 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a\" width=\"882\" height=\"552\" title=\"\" srcset=\"https:\/\/www.eghamat24.com\/blog\/wp-content\/uploads\/2024\/08\/New-Project-2024-08-09T163956.201.webp 882w, https:\/\/www.eghamat24.com\/blog\/wp-content\/uploads\/2024\/08\/New-Project-2024-08-09T163956.201-300x188.webp 300w, https:\/\/www.eghamat24.com\/blog\/wp-content\/uploads\/2024\/08\/New-Project-2024-08-09T163956.201-768x481.webp 768w\" sizes=\"(max-width: 882px) 100vw, 882px\" \/><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u0627\u06af\u0631 \u062f\u0631 \u0628\u0631\u0646\u0627\u0645\u0647 \u063a\u0630\u0627\u06cc\u06cc \u0634\u0645\u0627\u060c \u06af\u0648\u0634\u062a \u0633\u0647\u0645 \u0645\u0647\u0645 \u0648 \u0642\u0627\u0628\u0644 \u062a\u0648\u062c\u0647\u06cc \u062f\u0627\u0631\u062f\u060c \u0627\u0632 \u0634\u0645\u0627 \u0646\u0645\u06cc\u200c\u062e\u0648\u0627\u0647\u06cc\u0645 \u06a9\u0647 \u06cc\u06a9\u0628\u0627\u0631\u0647 \u062a\u0645\u0627\u0645 \u0645\u0648\u0627\u062f \u06af\u0648\u0634\u062a\u06cc \u0631\u0627 \u0627\u0632 \u0628\u0631\u0646\u0627\u0645\u0647 \u063a\u0630\u0627\u06cc\u06cc\u062a\u0627\u0646 \u062d\u0630\u0641 \u06a9\u0646\u06cc\u062f \u0627\u0645\u0627 \u0628\u0647 \u062a\u0639\u062f\u06cc\u0644 \u0622\u0646 \u0641\u06a9\u0631 \u06a9\u0646\u06cc\u062f \u062a\u0627 \u0647\u0645 \u0628\u062f\u0646 \u0633\u0627\u0644\u0645\u200c\u062a\u0631\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f \u0648 \u0647\u0645 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a \u0627\u0632 \u0627\u06cc\u0646 \u0646\u0638\u0631 \u0622\u0633\u06cc\u0628 \u06a9\u0645\u200c\u062a\u0631\u06cc \u0628\u0628\u06cc\u0646\u062f. \u0627\u06af\u0631 \u0645\u06cc\u200c\u062e\u0648\u0627\u0647\u06cc\u062f \u0628\u062f\u0627\u0646\u06cc\u062f \u06a9\u0647 <\/span><span style=\"font-weight: 400;\">\u0686\u06af\u0648\u0646\u06af\u06cc \u062d\u0641\u0627\u0638\u062a \u0627\u0632 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a \u0627\u0632 \u0637\u0631\u06cc\u0642 \u06af\u06cc\u0627\u0647\u200c\u062e\u0648\u0627\u0631\u06cc \u0686\u06cc\u0633\u062a\u060c \u0627\u0648\u0644 \u0628\u0647\u062a\u0631 \u0627\u0633\u062a \u0628\u0647 \u0622\u0646 \u0637\u0631\u0641 \u0642\u0636\u06cc\u0647 \u06cc\u0639\u0646\u06cc \u0622\u0633\u06cc\u0628\u200c\u0647\u0627\u06cc \u06af\u0648\u0634\u062a\u062e\u0648\u0627\u0631\u06cc \u0628\u0631 \u0633\u0644\u0627\u0645\u062a \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a \u0646\u06af\u0627\u0647\u06cc \u0628\u06cc\u0646\u062f\u0627\u0632\u06cc\u0645. \u0628\u0647 \u0637\u0648\u0631 \u06a9\u0644\u06cc \u0633\u0647\u0645 \u062f\u0627\u0645\u200c\u0647\u0627 \u062d\u062f\u0648\u062f \u06f8\u06f0 \u062f\u0631\u0635\u062f \u0627\u0632 \u0632\u0645\u06cc\u0646\u200c\u0647\u0627\u06cc \u06a9\u0634\u0627\u0648\u0631\u0632\u06cc \u062c\u0647\u0627\u0646 \u0627\u0633\u062a. \u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646 \u06af\u0648\u0634\u062a\u062e\u0648\u0627\u0631\u06cc \u0627\u0641\u0631\u0627\u0637\u06cc \u0632\u0645\u06cc\u0646 \u0628\u06cc\u0634\u062a\u0631\u06cc \u0631\u0627 \u0627\u0634\u063a\u0627\u0644 \u0645\u06cc\u200c\u06a9\u0646\u062f \u0648 \u062f\u0631 \u0646\u062a\u06cc\u062c\u0647 \u0628\u0627\u0639\u062b \u062c\u0627\u06cc \u06a9\u0645\u200c\u062a\u0631 \u0628\u0631\u0627\u06cc \u0633\u06a9\u0648\u0646\u062a \u0627\u0646\u0633\u0627\u0646\u200c\u0647\u0627 \u0648 \u062a\u062e\u0631\u06cc\u0628 \u0628\u06cc\u0634\u062a\u0631 \u062c\u0646\u06af\u0644\u200c\u0647\u0627 \u0645\u06cc\u200c\u0634\u0648\u062f. <\/span><span style=\"font-weight: 400;\">\u0622\u0646 \u0637\u0631\u0641 \u0642\u0636\u06cc\u0647\u060c \u06af\u06cc\u0627\u0647\u200c\u062e\u0648\u0627\u0631\u06cc \u0627\u0633\u062a \u06a9\u0647 \u06af\u06cc\u0627\u0647\u0627\u0646 \u0641\u0642\u0637 \u06f2\u06f3 \u062f\u0631\u0635\u062f \u0627\u0632 \u0632\u0645\u06cc\u0646\u200c\u0647\u0627\u06cc \u06a9\u0634\u0627\u0648\u0631\u0632\u06cc \u0631\u0627 \u0628\u0647 \u062e\u0648\u062f \u0627\u062e\u062a\u0635\u0627\u0635 \u062f\u0627\u062f\u0647\u200c\u0627\u0646\u062f. \u0628\u0627 \u0627\u06cc\u0646 \u0648\u062c\u0648\u062f\u060c \u06af\u06cc\u0627\u0647\u200c\u062e\u0648\u0627\u0631\u06cc \u0628\u0627\u0639\u062b \u0631\u0648\u06cc\u0634 \u0628\u06cc\u0634\u062a\u0631 \u06af\u06cc\u0627\u0647\u0627\u0646\u060c \u062a\u0648\u0644\u06cc\u062f \u0628\u06cc\u0634\u062a\u0631 \u0627\u06a9\u0633\u06cc\u0698\u0646 \u0648 \u06af\u0631\u0645\u0627\u06cc\u0634 \u06a9\u0645\u200c\u062a\u0631 \u0632\u0645\u06cc\u0646 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/span><\/p>\n<h2 style=\"text-align: justify;\"><b>\u0645\u0634\u0627\u0631\u06a9\u062a \u062f\u0631 \u06a9\u0645\u067e\u06cc\u0646\u200c\u0647\u0627\u06cc \u0645\u0633\u0626\u0648\u0644\u06cc\u062a \u0627\u062c\u062a\u0645\u0627\u0639\u06cc \u06cc\u0627 CSR<\/b><\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u06cc\u06a9 \u0631\u0648\u0634 \u062a\u0627\u062b\u06cc\u0631\u06af\u0630\u0627\u0631 \u0648 \u062e\u0644\u0627\u0642\u0627\u0646\u0647 \u0628\u0631\u0627\u06cc \u062d\u0641\u0627\u0638\u062a \u0627\u0632 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a \u0627\u06cc\u0646 \u0627\u0633\u062a \u06a9\u0647 \u06a9\u0645\u067e\u06cc\u0646\u200c\u0647\u0627\u06cc \u0645\u0633\u0626\u0648\u0644\u06cc\u062a\u200c \u0627\u062c\u062a\u0645\u0627\u0639\u06cc \u06cc\u0627 CSR\u00a0 \u0631\u0627\u0647 \u0628\u06cc\u0646\u062f\u0627\u0632\u06cc\u062f \u06cc\u0627 \u062f\u0631 \u0622\u0646\u200c\u0647\u0627 \u0645\u0634\u0627\u0631\u06a9\u062a \u06a9\u0646\u06cc\u062f. \u0628\u0631\u0627\u06cc \u0627\u0646\u062c\u0627\u0645 \u0627\u06cc\u0646 \u06a9\u0627\u0631 \u0644\u0627\u0632\u0645 \u0646\u06cc\u0633\u062a \u06a9\u0627\u0631\u0647\u0627\u06cc \u0633\u062e\u062a \u0648 \u067e\u06cc\u0686\u06cc\u062f\u0647\u200c\u0627\u06cc \u0628\u06a9\u0646\u06cc\u062f. \u0628\u0631\u0627\u06cc \u0645\u062b\u0627\u0644 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0627\u06cc\u0646\u0641\u0644\u0648\u0626\u0646\u0633\u0631\u0647\u0627 \u0648 \u06a9\u0646\u0634\u200c\u06af\u0631\u0647\u0627\u06cc \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a\u06cc \u0631\u0627 \u062f\u0631 \u0634\u0628\u06a9\u0647\u200c\u0647\u0627\u06cc \u0627\u062c\u062a\u0645\u0627\u0639\u06cc \u062f\u0646\u0628\u0627\u0644 \u06a9\u0646\u06cc\u062f \u0648 \u0628\u0628\u06cc\u0646\u06cc\u062f \u0622\u0646\u200c\u0647\u0627 \u0686\u0647 \u0641\u0639\u0627\u0644\u06cc\u062a\u200c\u0647\u0627\u06cc \u062f\u0633\u062a\u0647\u200c\u062c\u0645\u0639\u06cc \u0631\u0627 \u062f\u0631 \u062c\u0647\u062a \u062d\u0641\u0627\u0638\u062a \u0627\u0632 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a \u0627\u0646\u062c\u0627\u0645 \u0645\u06cc\u200c\u062f\u0647\u0646\u062f. \u0645\u062b\u0644\u0627 \u0627\u06cc\u0646 \u0627\u0641\u0631\u0627\u062f \u06af\u0627\u0647\u06cc \u062e\u0648\u0627\u0633\u062a\u0627\u0631 \u0641\u0639\u0627\u0644\u06cc\u062a \u0648 \u0645\u0634\u0627\u0631\u06a9\u062a \u0645\u0631\u062f\u0645 \u0628\u0631\u0627\u06cc \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0627\u0632 \u0642\u0637\u0639 \u062f\u0631\u062e\u062a\u0627\u0646 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f \u06cc\u0627 \u062a\u0644\u0627\u0634 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f \u062a\u062e\u0631\u06cc\u0628 \u0645\u0646\u0627\u0628\u0639 \u0637\u0628\u06cc\u0639\u06cc \u0645\u0627\u0646\u0646\u062f \u06a9\u0648\u0647 \u0628\u0631\u0627\u06cc \u0633\u0627\u062e\u062a\u200c\u0648\u0633\u0627\u0632 \u0628\u0647 \u062d\u062f\u0627\u0642\u0644 \u0628\u0631\u0633\u062f.<\/span><\/p>\n<h2 style=\"text-align: justify;\">\u06a9\u0627\u0634\u062a\u0646 \u062f\u0631\u062e\u062a \u0648 \u0646\u0647\u0627\u0644<\/h2>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-38096 size-full\" src=\"https:\/\/www.eghamat24.com\/blog\/wp-content\/uploads\/2024\/08\/New-Project-60.webp\" alt=\"\u062f\u0631\u062e\u062a\u06a9\u0627\u0631\u06cc \u0631\u0627\u0647\u06cc \u0633\u0627\u062f\u0647 \u0648 \u0645\u0648\u062b\u0631 \u0628\u0631\u0627\u06cc \u062d\u0641\u0627\u0638\u062a \u0627\u0632 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a\" width=\"882\" height=\"552\" title=\"\" srcset=\"https:\/\/www.eghamat24.com\/blog\/wp-content\/uploads\/2024\/08\/New-Project-60.webp 882w, https:\/\/www.eghamat24.com\/blog\/wp-content\/uploads\/2024\/08\/New-Project-60-300x188.webp 300w, https:\/\/www.eghamat24.com\/blog\/wp-content\/uploads\/2024\/08\/New-Project-60-768x481.webp 768w\" sizes=\"(max-width: 882px) 100vw, 882px\" \/><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u0634\u0627\u06cc\u062f \u0627\u06cc\u0646 \u062a\u0648\u0635\u06cc\u0647\u200c \u0631\u0627 \u0627\u0632 \u06a9\u0648\u062f\u06a9\u06cc \u062a\u0627 \u0628\u0647 \u0627\u0644\u0627\u0646 \u0647\u0632\u0627\u0631\u0627\u0646 \u0628\u0627\u0631 \u0634\u0646\u06cc\u062f\u0647 \u0628\u0627\u0634\u06cc\u062f \u06a9\u0647 \u0628\u0631\u0627\u06cc \u062d\u0641\u0627\u0638\u062a \u0627\u0632 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a\u060c \u062f\u0631\u062e\u062a \u0628\u06a9\u0627\u0631\u06cc\u062f. \u0627\u0645\u0627 \u0686\u0631\u0627 \u062f\u0631\u062e\u062a\u200c\u06a9\u0627\u0631\u06cc \u06cc\u06a9\u06cc \u0627\u0632 \u0631\u0627\u0647 \u0647\u0627\u06cc \u062d\u0641\u0638 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a \u0627\u0633\u062a\u061f \u062f\u0644\u0627\u06cc\u0644 \u0627\u06cc\u0646 \u0645\u0648\u0636\u0648\u0639 \u0631\u0627 \u062f\u0631 \u0642\u0633\u0645\u062a \u0632\u06cc\u0631 \u0628\u062e\u0648\u0627\u0646\u06cc\u062f:<\/span><\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u062f\u0631\u062e\u062a\u200c\u06a9\u0627\u0631\u06cc \u0648 \u0648\u062c\u0648\u062f \u062f\u0631\u062e\u062a\u0627\u0646 \u0628\u0627\u0639\u062b \u062a\u0648\u0644\u06cc\u062f \u0647\u0631 \u0686\u0647 \u0628\u06cc\u0634\u062a\u0631 \u0627\u06a9\u0633\u06cc\u0698\u0646 \u0648 \u06a9\u0627\u0647\u0634 \u0622\u0644\u0627\u06cc\u0646\u062f\u0647\u200c\u0647\u0627 \u062f\u0631 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a \u0645\u06cc\u200c\u0634\u0648\u062f.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u06a9\u0627\u0634\u062a \u062f\u0631\u062e\u062a\u0627\u0646 \u0628\u0647 \u062a\u0639\u0627\u062f\u0644 \u062f\u0645\u0627\u06cc \u0647\u0648\u0627 \u06a9\u0645\u06a9 \u0645\u06cc\u200c\u06a9\u0646\u062f \u062a\u0627 \u06a9\u0645\u200c\u062a\u0631 \u0634\u0627\u0647\u062f \u0627\u0641\u0632\u0627\u06cc\u0634 \u0648 \u06a9\u0627\u0647\u0634 \u0646\u0627\u06af\u0647\u0627\u0646\u06cc \u0647\u0648\u0627 \u0628\u0627\u0634\u06cc\u0645.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u062f\u0631\u062e\u062a\u0627\u0646 \u0648 \u067e\u0648\u0634\u0634 \u06af\u06cc\u0627\u0647\u06cc \u062f\u0631 \u062c\u0646\u06af\u0644\u200c\u0647\u0627 \u0645\u0627\u0646\u0639 \u0628\u0631\u0648\u0632 \u062e\u0633\u0627\u0631\u062a\u200c\u0647\u0627\u06cc \u0633\u0646\u06af\u06cc\u0646 \u0646\u0627\u0634\u06cc \u0627\u0632 \u0633\u06cc\u0644 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f. \u0628\u0647 \u0627\u06cc\u0646 \u0635\u0648\u0631\u062a \u06a9\u0647 \u0630\u0631\u0627\u062a \u0622\u0628 \u0628\u0647 \u0634\u0627\u062e \u0648 \u0628\u0631\u06af \u062f\u0631\u062e\u062a\u0627\u0646 \u0628\u0631\u062e\u0648\u0631\u062f \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f \u0648 \u0627\u0632 \u0634\u062f\u062a \u0648 \u0633\u0631\u0639\u062a\u0634\u0627\u0646 \u06a9\u0645 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0648\u062c\u0648\u062f \u0628\u06cc\u0634\u062a\u0631 \u062f\u0631\u062e\u062a\u0627\u0646 \u062f\u0631 \u0637\u0628\u06cc\u0639\u062a \u0628\u0627\u0639\u062b \u0645\u06cc\u200c\u0634\u0648\u062f \u062a\u0627 \u062d\u06cc\u0648\u0627\u0646\u0627\u062a \u067e\u0646\u0627\u0647\u06af\u0627\u0647\u200c\u0647\u0627\u06cc \u0628\u06cc\u0634\u062a\u0631\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u0646\u062f.<\/span><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">\u0645\u0628\u0627\u0631\u0632\u0647 \u0628\u0627 \u062c\u0646\u06af\u0644\u200c\u0632\u062f\u0627\u06cc\u06cc<\/h2>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-38097 size-full\" src=\"https:\/\/www.eghamat24.com\/blog\/wp-content\/uploads\/2024\/08\/New-Project-62.webp\" alt=\"\u0645\u0628\u0627\u0631\u0632\u0647 \u0628\u0627 \u062c\u0646\u06af\u0644\u200c\u0632\u062f\u0627\u06cc\u06cc \u0628\u0631\u0627\u06cc \u062d\u0641\u0627\u0638\u062a \u0627\u0632 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a\" width=\"882\" height=\"552\" title=\"\" srcset=\"https:\/\/www.eghamat24.com\/blog\/wp-content\/uploads\/2024\/08\/New-Project-62.webp 882w, https:\/\/www.eghamat24.com\/blog\/wp-content\/uploads\/2024\/08\/New-Project-62-300x188.webp 300w, https:\/\/www.eghamat24.com\/blog\/wp-content\/uploads\/2024\/08\/New-Project-62-768x481.webp 768w\" sizes=\"(max-width: 882px) 100vw, 882px\" \/><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u0647\u0645\u0627\u0646\u200c\u0637\u0648\u0631 \u06a9\u0647 \u062f\u0631\u062e\u062a\u200c\u06a9\u0627\u0631\u06cc \u0628\u0627\u0639\u062b \u062d\u0641\u0627\u0638\u062a \u0627\u0632 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a \u0645\u06cc\u200c\u0634\u0648\u062f\u060c \u0637\u0628\u06cc\u0639\u06cc \u0627\u0633\u062a \u06a9\u0647 \u062c\u0646\u06af\u0644\u200c\u0632\u062f\u0627\u06cc\u06cc \u0628\u0627\u0639\u062b \u0622\u0633\u06cc\u0628 \u0628\u0647 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a \u0634\u0648\u062f. \u0627\u06cc\u0646 \u0631\u0648\u0632\u0647\u0627 \u0645\u062a\u0627\u0633\u0641\u0627\u0646\u0647 \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0627\u0641\u0631\u0627\u062f \u0648 \u0633\u0627\u0632\u0645\u0627\u0646\u200c\u0647\u0627 \u0628\u0631\u0627\u06cc \u0645\u0646\u0627\u0641\u0639 \u0634\u062e\u0635\u06cc \u062e\u0648\u062f \u0645\u0646\u0627\u0628\u0639 \u0637\u0628\u06cc\u0639\u06cc \u0645\u062b\u0644 \u062c\u0646\u06af\u0644 \u0631\u0627 \u0627\u0632 \u0628\u06cc\u0646 \u0645\u06cc\u200c\u0628\u0631\u0646\u062f \u062a\u0627 \u0634\u0627\u06cc\u062f \u062c\u0627\u062f\u0647\u200c\u0627\u06cc \u0628\u0633\u0627\u0632\u0646\u062f\u060c \u06a9\u0633\u0628\u200c\u0648\u06a9\u0627\u0631\u06cc \u0628\u0631\u067e\u0627 \u06a9\u0646\u0646\u062f \u06cc\u0627 \u0648\u0633\u0627\u06cc\u0644 \u0686\u0648\u0628\u06cc \u062a\u0648\u0644\u06cc\u062f \u06a9\u0646\u0646\u062f. \u0628\u0647 \u0647\u0631 \u062d\u0627\u0644 \u0647\u062f\u0641 \u0647\u0631 \u0686\u0647 \u06a9\u0647 \u0628\u0627\u0634\u062f \u0646\u0628\u0627\u06cc\u062f \u067e\u0648\u0634\u0634 \u06af\u06cc\u0627\u0647\u06cc \u0648 \u0632\u06cc\u0633\u062a\u06af\u0627\u0647 \u062c\u0627\u0646\u0648\u0631\u0627\u0646 \u0631\u0627 \u0641\u062f\u0627\u06cc \u062e\u0648\u0627\u0633\u062a\u0647\u200c\u0647\u0627\u06cc \u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u062f\u0627\u0631\u06cc \u062e\u0648\u062f \u06a9\u0646\u06cc\u0645 \u0648 \u0628\u0627 \u0642\u0648\u0627\u06cc \u0647\u0631 \u0686\u0647 \u062a\u0645\u0627\u0645\u200c\u062a\u0631 \u0628\u0627\u06cc\u062f \u0627\u06cc\u0646 \u06af\u0646\u062c\u200c\u0647\u0627\u06cc \u0633\u0628\u0632 \u0632\u0645\u06cc\u0646 \u0631\u0627 \u062d\u0641\u0638 \u06a9\u0646\u06cc\u0645.<\/span><\/p>\n<h2 style=\"text-align: justify;\">\u0647\u0634\u06cc\u0627\u0631\u0628\u0648\u062f\u0646 \u062f\u0631 \u0628\u0631\u0627\u0628\u0631 \u0634\u06a9\u0627\u0631 \u063a\u06cc\u0631\u0642\u0627\u0646\u0648\u0646\u06cc<\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u0627\u06cc\u0646 \u0644\u0642\u0628 \u0627\u0634\u0631\u0641 \u0645\u062e\u0644\u0648\u0642\u0627\u062a\u200c\u0628\u0648\u062f\u0646 \u0645\u062a\u0627\u0633\u0641\u0627\u0646\u0647 \u062f\u0631 \u0628\u0639\u0636\u06cc \u0627\u0632 \u0627\u0641\u0631\u0627\u062f \u0627\u06cc\u0646 \u062a\u0648\u0647\u0645 \u0631\u0627 \u0628\u0647 \u0648\u062c\u0648\u062f \u0622\u0648\u0631\u062f\u0647 \u06a9\u0647 \u0627\u062c\u0627\u0632\u0647 \u062f\u0627\u0631\u0646\u062f \u062f\u0631 \u0637\u0628\u06cc\u0639\u062a \u0647\u0631 \u062f\u062e\u0644 \u0648 \u062a\u0635\u0631\u0641\u06cc \u0628\u06a9\u0646\u0646\u062f \u0648 \u062d\u062a\u06cc \u062c\u0627\u0646 \u0645\u0648\u062c\u0648\u062f\u0627\u062a \u0632\u0646\u062f\u0647 \u0631\u0627 \u0628\u06af\u06cc\u0631\u0646\u062f. \u0647\u0631 \u0632\u0645\u0627\u0646 \u06a9\u0647 \u062f\u0631 \u062c\u0627\u06cc\u06cc \u0627\u0632 \u0637\u0628\u06cc\u0639\u062a \u06cc\u0627 \u062f\u0631 \u0645\u06cc\u0627\u0646 \u0627\u0637\u0631\u0627\u0641\u06cc\u0627\u0646\u062a\u0627\u0646 \u062d\u0633 \u06a9\u0631\u062f\u06cc\u062f \u06a9\u0647 \u0634\u06a9\u0627\u0631 \u063a\u06cc\u0631 \u0642\u0627\u0646\u0648\u0646\u06cc \u0627\u0646\u062c\u0627\u0645 \u0645\u06cc\u200c\u0634\u0648\u062f\u060c \u0628\u06cc\u200c\u062f\u0631\u0646\u06af \u0622\u0646 \u0631\u0627 \u0628\u0627 \u0633\u0627\u0645\u0627\u0646\u0647 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a\u06cc \u0628\u0647 \u0634\u0645\u0627\u0631\u0647 \u062a\u0644\u0641\u0646 \u06f1\u06f5\u06f4\u06f0 \u062f\u0631\u0645\u06cc\u0627\u0646 \u0628\u06af\u0630\u0627\u0631\u06cc\u062f.<\/span><\/p>\n<h2 style=\"text-align: justify;\"><b>\u0631\u0647\u0627\u0646\u06a9\u0631\u062f\u0646 \u0645\u0627\u0647\u06cc\u200c\u0647\u0627\u06cc \u0642\u0631\u0645\u0632 \u062f\u0631 \u0622\u0628\u200c\u0647\u0627\u06cc \u0622\u0632\u0627\u062f \u0648 \u0631\u0648\u062f\u062e\u0627\u0646\u0647\u200c\u0647\u0627<\/b><\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u0633\u0627\u0644\u0627\u0646\u0647 \u0645\u06cc\u0644\u06cc\u0648\u0646\u200c\u0647\u0627 \u0645\u0627\u0647\u06cc \u0642\u0631\u0645\u0632 \u0628\u0647 \u062e\u0627\u0637\u0631 \u06cc\u06a9 \u0631\u0633\u0645 \u063a\u0644\u0637 \u0646\u0648\u0631\u0648\u0632\u06cc \u0645\u06cc\u200c\u0645\u06cc\u0631\u0646\u062f\u060c \u067e\u0633 \u0628\u06cc\u0627\u06cc\u06cc\u062f \u0627\u0648\u0644 \u0628\u0647 \u0627\u0635\u0644 \u062e\u0631\u06cc\u062f\u0646 \u0645\u0627\u0647\u06cc \u0642\u0631\u0645\u0632 \u0634\u06a9 \u06a9\u0646\u06cc\u0645. \u0628\u0627 \u0627\u06cc\u0646 \u062d\u0627\u0644 \u0627\u06af\u0631 \u0632\u0645\u0627\u0646\u06cc \u0645\u0627\u0647\u06cc \u0642\u0631\u0645\u0632 \u062e\u0631\u06cc\u062f\u06cc\u062f\u060c \u0622\u0646 \u0631\u0627 \u062f\u0631\u0648\u0646 \u0631\u0648\u062f\u062e\u0627\u0646\u0647 \u0631\u0647\u0627 \u0646\u06a9\u0646\u06cc\u062f \u0632\u06cc\u0631\u0627 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0633\u0644\u0627\u0645\u062a \u0622\u0628\u0632\u06cc\u0627\u0646 \u062f\u06cc\u06af\u0631 \u0631\u0627 \u0628\u0627 \u0627\u0646\u062a\u0642\u0627\u0644 \u0628\u06cc\u0645\u0627\u0631\u06cc \u0628\u0647 \u062e\u0637\u0631 \u0628\u06cc\u0646\u062f\u0627\u0632\u062f.<\/span><\/p>\n<h2 style=\"text-align: justify;\"><b>\u0686\u0637\u0648\u0631 \u062f\u0631 \u062e\u0627\u0646\u0647 \u0627\u0632 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a \u062d\u0641\u0627\u0638\u062a \u06a9\u0646\u06cc\u0645\u061f<\/b><\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u0628\u0631\u0627\u06cc \u062d\u0641\u0627\u0638\u062a \u0627\u0632 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a \u062f\u0631 \u062e\u0627\u0646\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u06cc\u062f \u0631\u0627\u0647\u06a9\u0627\u0631\u0647\u0627\u06cc \u0632\u06cc\u0631 \u0631\u0627 \u0628\u0647 \u06a9\u0627\u0631 \u0628\u06af\u06cc\u0631\u06cc\u062f:<\/span><\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u067e\u0633\u0645\u0627\u0646\u062f\u0647\u0627\u06cc \u062a\u0631 \u0645\u0648\u0627\u062f\u063a\u0630\u0627\u06cc\u06cc \u062e\u0648\u062f \u0631\u0627 \u062f\u0631 \u0645\u0639\u0631\u0636 \u06af\u0631\u0645\u0627\u06cc \u0628\u06cc\u0631\u0648\u0646 \u06cc\u0627 \u0634\u0648\u0641\u0627\u0698 \u0642\u0631\u0627\u0631 \u062f\u0647\u06cc\u062f \u0648 \u0627\u0632 \u0622\u0646\u200c\u0647\u0627 <\/span><b>\u062e\u0634\u06a9\u0627\u0644\u0647 <\/b><span style=\"font-weight: 400;\">\u062a\u0648\u0644\u06cc\u062f \u06a9\u0646\u06cc\u062f. \u0627\u06cc\u0646 \u062e\u0634\u06a9\u0627\u0644\u0647\u200c\u0647\u0627 \u0631\u0627 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u063a\u0630\u0627\u06cc \u062f\u0627\u0645 \u0648 \u06a9\u0645\u067e\u0648\u0633\u062a \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0631\u062f \u06cc\u0627 \u062d\u062a\u06cc \u0627\u06af\u0631 \u0622\u0646\u200c\u0647\u0627 \u0631\u0627 \u062f\u0648\u0631 \u0628\u06cc\u0646\u062f\u0627\u0632\u06cc\u062f\u060c \u0627\u06cc\u0646 \u0641\u0627\u06cc\u062f\u0647 \u0631\u0627 \u062f\u0627\u0631\u062f \u06a9\u0647 \u062f\u06cc\u06af\u0631 \u0632\u0628\u0627\u0644\u0647\u200c\u0647\u0627\u06cc\u062a\u0627\u0646 \u0622\u0644\u0648\u062f\u0647 \u0628\u0647 \u0634\u06cc\u0631\u0627\u0628\u0647\u200c \u0646\u062e\u0648\u0627\u0647\u062f \u0628\u0648\u062f.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0632\u0628\u0627\u0644\u0647\u200c\u0647\u0627\u06cc \u062a\u0631 \u0648 \u062e\u0634\u06a9 \u062e\u0648\u062f \u0631\u0627 \u0628\u0627\u0632\u06cc\u0627\u0641\u062a \u06a9\u0646\u06cc\u062f.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u062f\u0631 \u0645\u0635\u0631\u0641 \u0634\u0648\u06cc\u0646\u062f\u0647\u200c\u062c\u0627\u062a \u0635\u0631\u0641\u0647\u200c\u062c\u0648\u06cc\u06cc \u06a9\u0646\u06cc\u062f.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0628\u0647 \u062c\u0627\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u06a9\u06cc\u0633\u0647 \u0641\u0631\u06cc\u0632\u0631 \u0627\u0632 \u0638\u0631\u0648\u0641 \u0645\u0642\u0627\u0648\u0645 \u067e\u0644\u0627\u0633\u062a\u06cc\u06a9\u06cc \u062f\u0631 \u0628\u0631\u0627\u0628\u0631 \u062f\u0645\u0627\u06cc \u0628\u0627\u0644\u0627 \u0648 \u067e\u0627\u06cc\u06cc\u0646 \u06cc\u0627 \u0638\u0631\u0641\u200c\u0647\u0627\u06cc \u0634\u06cc\u0634\u0647\u200c\u0627\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0645\u0648\u0627\u062f \u063a\u0630\u0627\u06cc\u06cc \u0648 \u0634\u0648\u06cc\u0646\u062f\u0647 \u0645\u0648\u0631\u062f \u0646\u06cc\u0627\u0632 \u062e\u0648\u062f \u0631\u0627 \u062f\u0631 \u0642\u0627\u0644\u0628 \u0628\u0633\u062a\u0647\u200c\u0628\u0646\u062f\u06cc\u200c\u0647\u0627\u06cc \u0628\u0632\u0631\u06af \u06cc\u0627 \u0628\u0647 \u0635\u0648\u0631\u062a \u0641\u0644\u0647 \u062a\u0647\u06cc\u0647 \u06a9\u0646\u06cc\u062f.<\/span><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\"><b>\u0686\u0637\u0648\u0631 \u062f\u0631 \u0645\u062d\u0644 \u06a9\u0627\u0631 \u0627\u0632 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u0645\u061f<\/b><\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u0628\u0631\u0627\u06cc \u062d\u0641\u0627\u0638\u062a \u0627\u0632 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a \u062f\u0631 \u0645\u062d\u0644 \u06a9\u0627\u0631 \u062e\u0648\u0628 \u0627\u0633\u062a \u0645\u0648\u0627\u0631\u062f \u0632\u06cc\u0631 \u0631\u0627 \u0631\u0639\u0627\u06cc\u062a \u06a9\u0646\u06cc\u062f:<\/span><\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0627\u0632 \u0648\u0633\u0627\u06cc\u0644 \u0627\u0644\u06a9\u062a\u0631\u0648\u0646\u06cc\u06a9\u06cc \u0648 \u062a\u06a9\u0646\u0648\u0644\u0648\u0698\u06cc \u0628\u0647 \u062c\u0627\u06cc \u06a9\u0627\u063a\u0630 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0628\u0647 \u062c\u0627\u06cc \u0633\u0641\u0627\u0631\u0634 \u063a\u0630\u0627 \u0627\u0632 \u0628\u06cc\u0631\u0648\u0646\u060c \u063a\u0630\u0627\u06cc \u062e\u0627\u0646\u06af\u06cc \u0645\u06cc\u0644 \u06a9\u0646\u06cc\u062f.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u062f\u0631 \u0635\u0648\u0631\u062a \u0627\u0633\u062a\u0639\u0645\u0627\u0644 \u062f\u062e\u0627\u0646\u06cc\u0627\u062a\u060c \u062a\u0647\u200c\u0633\u06cc\u06af\u0627\u0631 \u062e\u0648\u062f \u0631\u0627 \u062f\u0631\u0648\u0646 \u0633\u0637\u0644 \u0622\u0634\u063a\u0627\u0644 \u0628\u06cc\u0646\u062f\u0627\u0632\u06cc\u062f.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u062d\u062a\u06cc\u200c\u0627\u0644\u0627\u0645\u06a9\u0627\u0646 \u0627\u0632 \u0686\u0627\u06cc \u062f\u0645\u06cc \u0628\u0647 \u062c\u0627\u06cc \u0686\u0627\u06cc \u06a9\u06cc\u0633\u0647\u200c\u0627\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u062f\u0631 \u0645\u062d\u06cc\u0637 \u06a9\u0627\u0631\u060c \u0638\u0631\u0648\u0641 \u0634\u062e\u0635\u06cc \u0628\u0647 \u0647\u0645\u0631\u0627\u0647 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u06cc\u062f \u062a\u0627 \u0646\u0627\u0686\u0627\u0631 \u0628\u0647 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0638\u0631\u0648\u0641 \u06cc\u06a9\u0628\u0627\u0631 \u0645\u0635\u0631\u0641 \u0646\u0634\u0648\u06cc\u062f.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u062f\u0631 \u0635\u0648\u0631\u062a \u0627\u0645\u06a9\u0627\u0646 \u0627\u0632 \u0648\u0633\u0627\u06cc\u0644\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0634\u0648\u062f \u06a9\u0647 \u06a9\u0645\u200c\u062a\u0631\u06cc\u0646 \u0645\u06cc\u0632\u0627\u0646 \u0645\u0635\u0631\u0641 \u0627\u0646\u0631\u0698\u06cc \u0631\u0627 \u062f\u0627\u0631\u0646\u062f.<\/span><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\"><b>\u062f\u0627\u0646\u0634 \u0622\u0645\u0648\u0632\u0627\u0646 \u0686\u0637\u0648\u0631 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0627\u0632 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a \u062d\u0641\u0627\u0638\u062a \u06a9\u0646\u0646\u062f\u061f<\/b><\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u0627\u06af\u0631 \u0628\u0631\u0627\u06cc \u0634\u0645\u0627 \u0633\u0648\u0627\u0644 \u0627\u0633\u062a \u06a9\u0647 \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u06cc\u06a9 \u062f\u0627\u0646\u0634 \u0622\u0645\u0648\u0632 <\/span><span style=\"font-weight: 400;\">\u0628\u0631\u0627\u06cc \u062d\u0641\u0627\u0638\u062a \u0627\u0632 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a \u0686\u0647 \u0627\u0642\u062f\u0627\u0645\u0627\u062a\u06cc \u0645\u06cc\u062a\u0648\u0627\u0646 \u0627\u0646\u062c\u0627\u0645 \u062f\u0627\u062f\u060c \u0642\u0633\u0645\u062a \u0632\u06cc\u0631 \u0631\u0627 \u0628\u062e\u0648\u0627\u0646\u06cc\u062f:<\/span><\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0632\u0628\u0627\u0644\u0647 \u062e\u0648\u062f \u0631\u0627 \u062d\u062a\u0645\u0627 \u062f\u0631 \u0633\u0637\u0644 \u0622\u0634\u063a\u0627\u0644 \u0628\u06cc\u0646\u062f\u0627\u0632\u06cc\u062f.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0628\u0647 \u062c\u0627\u06cc \u062e\u0631\u06cc\u062f \u062e\u0648\u0631\u0627\u06a9\u06cc\u200c\u0647\u0627\u06cc \u0646\u0627\u0633\u0627\u0644\u0645\u060c \u062e\u0648\u0631\u0627\u06a9\u06cc \u0633\u0627\u0644\u0645 \u0627\u0632 \u0645\u0646\u0632\u0644 \u0647\u0645\u0631\u0627\u0647 \u062e\u0648\u062f \u0628\u06cc\u0627\u0648\u0631\u06cc\u062f.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0627\u06af\u0631 \u062f\u0631\u062e\u062a \u06cc\u0627 \u06af\u06cc\u0627\u0647\u06cc \u062f\u0631 \u062d\u06cc\u0627\u0637 \u0645\u062f\u0631\u0633\u0647 \u0634\u0645\u0627 \u0645\u06cc\u200c\u0631\u0648\u06cc\u062f\u060c \u0627\u0632 \u0622\u0646 \u0645\u0631\u0627\u0642\u0628\u062a \u06a9\u0646\u06cc\u062f \u0648 \u062d\u0648\u0627\u0633\u062a\u0627\u0646 \u0628\u0627\u0634\u062f \u06a9\u0647 \u0622\u0633\u06cc\u0628\u06cc \u0646\u0628\u06cc\u0646\u062f \u0648 \u06af\u0644 \u0648 \u06af\u06cc\u0627\u0647\u06cc \u0631\u0627 \u0646\u0686\u06cc\u0646\u06cc\u062f.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u062f\u0631 \u0635\u0648\u0631\u062a\u06cc \u06a9\u0647 \u0645\u062f\u0631\u0633\u0647 \u0634\u0645\u0627 \u0641\u0636\u0627\u06cc \u0628\u0627\u063a\u0686\u0647\u200c\u0645\u0627\u0646\u0646\u062f \u062f\u0627\u0631\u062f\u060c \u0628\u0627 \u0627\u062c\u0627\u0632\u0647 \u0648 \u0635\u0644\u0627\u062d \u0645\u062f\u06cc\u0631\u0627\u0646 \u0648 \u0645\u0631\u0628\u06cc\u0627\u0646 \u062e\u0648\u062f \u062f\u0631 \u0627\u06cc\u0646 \u0641\u0636\u0627 \u06af\u06cc\u0627\u0647 \u0628\u06a9\u0627\u0631\u06cc\u062f.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0627\u0632 \u0644\u06cc\u0648\u0627\u0646 \u0648 \u0645\u0627\u06af \u0634\u062e\u0635\u06cc \u0628\u0647 \u062c\u0627\u06cc \u0644\u06cc\u0648\u0627\u0646 \u067e\u0644\u0627\u0633\u062a\u06cc\u06a9\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u062f\u0631 \u062d\u062f \u0646\u06cc\u0627\u0632 \u0627\u0632 \u0644\u0648\u0627\u0632\u0645\u200c\u0627\u0644\u062a\u062d\u0631\u06cc\u0631\u060c \u0628\u0647 \u062e\u0635\u0648\u0635 \u06a9\u0627\u063a\u0630 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u062f.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0628\u0647 \u062c\u0627\u06cc \u062f\u0648\u0631\u0627\u0646\u062f\u0627\u062e\u062a\u0646 \u062e\u06cc\u0644\u06cc \u0627\u0632 \u0648\u0633\u0627\u06cc\u0644\u062a\u0627\u0646\u060c \u0622\u0646\u200c\u0647\u0627 \u0631\u0627 \u0628\u0647 \u06a9\u0627\u0631\u062f\u0633\u062a\u06cc \u062a\u0628\u062f\u06cc\u0644 \u06a9\u0646\u06cc\u062f.<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u062f\u0631 \u0645\u0635\u0631\u0641 \u0622\u0628 \u0635\u0631\u0641\u0647\u200c\u062c\u0648\u06cc\u06cc \u06a9\u0646\u06cc\u062f.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">\u06a9\u062a\u0627\u0628\u200c\u0647\u0627\u06cc\u06cc \u0645\u0627\u0646\u0646\u062f <\/span><b>\u00ab\u062a\u063a\u06cc\u06cc\u0631\u0627\u062a \u0622\u0628 \u0648 \u0647\u0648\u0627\u06cc \u06a9\u0631\u0647\u200c\u06cc \u0632\u0645\u06cc\u0646: \u0627\u0641\u0632\u0627\u06cc\u0634 \u06a9\u0631\u0628\u0646\u200c\u062f\u06cc\u200c\u0627\u06a9\u0633\u06cc\u062f\u00bb<\/b> \u0631\u0627 \u0628\u062e\u0648\u0627\u0646\u06cc\u062f \u062a\u0627 \u062f\u0631\u0628\u0627\u0631\u0647 \u0632\u0645\u06cc\u0646 \u0648 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a \u0628\u062a\u0648\u0627\u0646\u06cc\u062f \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u0645\u0641\u06cc\u062f\u06cc \u0631\u0627 \u06a9\u0633\u0628 \u06a9\u0646\u06cc\u062f.<\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">\u0628\u0631\u0627\u06cc \u0628\u0642\u0627\u06cc \u062e\u0648\u062f\u062a\u0627\u0646\u060c \u0622\u06cc\u0646\u062f\u06af\u0627\u0646 \u0648 \u0645\u0648\u062c\u0648\u062f\u0627\u062a \u0632\u0646\u062f\u0647 \u0627\u0632 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a \u0645\u0631\u0627\u0642\u0628\u062a \u06a9\u0646\u06cc\u062f<\/h2>\n<p style=\"text-align: justify;\">\u0645\u0647\u0645\u200c\u062a\u0631\u06cc\u0646 \u0648 \u0627\u0648\u0644\u06cc\u0646 \u0642\u062f\u0645 \u0628\u0631\u0627\u06cc \u062d\u0641\u0627\u0638\u062a \u0627\u0632 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a \u0627\u06cc\u0646 \u0627\u0633\u062a \u06a9\u0647 \u0628\u0641\u0647\u0645\u06cc\u0645 \u06a9\u0631\u0647 \u0632\u0645\u06cc\u0646 \u0641\u0642\u0637 \u0628\u0647 \u0645\u0627 \u0627\u0646\u0633\u0627\u0646\u200c\u0647\u0627 \u062a\u0639\u0644\u0642 \u0646\u062f\u0627\u0631\u062f \u0648 \u0627\u06cc\u0646 \u0632\u0645\u06cc\u0646 \u0645\u062a\u0639\u0644\u0642 \u0628\u0647 \u062a\u0645\u0627\u0645 \u0645\u0648\u062c\u0648\u062f\u0627\u062a \u0632\u0646\u062f\u0647 \u0627\u0633\u062a. \u0627\u06af\u0631 \u0645\u0627 \u0645\u0631\u0627\u0642\u0628 \u0645\u0648\u062c\u0648\u062f\u0627\u062a \u0632\u0646\u062f\u0647 \u0648 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a \u0628\u0627\u0634\u06cc\u0645\u060c \u062f\u0631\u0648\u0627\u0642\u0639 \u0628\u0647 \u0641\u06a9\u0631 \u0633\u0644\u0627\u0645\u062a \u062e\u0648\u062f\u0645\u0627\u0646 \u0648 \u0622\u06cc\u0646\u062f\u06af\u0627\u0646\u0645\u0627\u0646 \u0628\u0648\u062f\u0647\u200c\u0627\u06cc\u0645. \u067e\u0633 \u06cc\u0627\u062f\u062a\u0627\u0646 \u0628\u0627\u0634\u062f \u0642\u062f\u0645 \u0627\u0648\u0644 \u0622\u06af\u0627\u0647\u06cc \u0627\u0633\u062a \u0648 \u0628\u0639\u062f \u0642\u062f\u0645\u200c\u0647\u0627\u06cc \u06a9\u0648\u0686\u06a9\u200c\u0628\u0631\u062f\u0627\u0634\u062a\u0646 \u0645\u062b\u0644 \u0628\u06cc\u0631\u0648\u0646 \u0646\u06cc\u0627\u0646\u062f\u0627\u062e\u062a\u0646 \u0632\u0628\u0627\u0644\u0647\u060c \u0635\u0631\u0641\u0647\u200c\u062c\u0648\u06cc\u06cc \u062f\u0631 \u0645\u0635\u0631\u0641 \u0627\u0646\u0631\u0698\u06cc\u060c \u0639\u062f\u0645 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u067e\u0644\u0627\u0633\u062a\u06cc\u06a9 \u0648&#8230; \u0627\u0633\u062a.<\/p>\n<p style=\"text-align: justify;\">\u0634\u0645\u0627 \u0628\u0631\u0627\u06cc \u062d\u0641\u0627\u0638\u062a \u0627\u0632 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a \u0686\u0647 \u0642\u062f\u0645\u06cc \u0628\u0631\u0645\u06cc\u200c\u062f\u0627\u0631\u06cc\u062f \u062a\u0627 \u0632\u0645\u06cc\u0646\u0645\u0627\u0646 \u0633\u0628\u0632\u062a\u0631 \u0628\u0647 \u062d\u06cc\u0627\u062a \u062e\u0648\u062f \u0627\u062f\u0627\u0645\u0647 \u062f\u0647\u062f\u061f<\/p>\n<h2 style=\"text-align: justify;\">\u0633\u0648\u0627\u0644\u0627\u062a \u0645\u062a\u062f\u0627\u0648\u0644<\/h2>\n<p style=\"text-align: justify;\"><div id=\"rank-math-rich-snippet-wrapper\"><div id=\"rank-math-faq\" class=\"rank-math-block\">\n<div class=\"rank-math-list \">\n<div id=\"faq-1\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \">\u0628\u0631\u0627\u06cc \u062d\u0641\u0627\u0638\u062a \u0627\u0632 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a \u0686\u0647 \u0628\u0627\u06cc\u062f \u06a9\u0631\u062f\u061f<\/h3>\n<div class=\"rank-math-answer \">\n\n<p> \u0635\u0631\u0641\u0647\u200c\u062c\u0648\u06cc\u06cc \u062f\u0631 \u0645\u0635\u0631\u0641 \u0627\u0646\u0631\u0698\u06cc\u060c \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u06a9\u06cc\u0633\u0647 \u067e\u0627\u0631\u0686\u0647\u200c\u0627\u06cc \u0628\u0647 \u062c\u0627\u06cc \u067e\u0644\u0627\u0633\u062a\u06cc\u06a9\u06cc \u0648 \u0631\u0641\u062a\u200c\u0648\u0622\u0645\u062f \u0628\u0627 \u0648\u0633\u0627\u06cc\u0644 \u062d\u0645\u0644\u200c\u0648\u0646\u0642\u0644 \u0639\u0645\u0648\u0645\u06cc \u0648...<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-2\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \">\u0686\u06af\u0648\u0646\u0647 \u0627\u0632 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a \u0645\u062d\u0627\u0641\u0638\u062a \u06a9\u0646\u06cc\u0645\u061f<\/h3>\n<div class=\"rank-math-answer \">\n\n<p>\u0628\u0627 \u0645\u0635\u0631\u0641 \u06a9\u0645\u200c\u062a\u0631\u060c \u062a\u0641\u06a9\u06cc\u06a9 \u0632\u0628\u0627\u0644\u0647\u200c\u0647\u0627\u060c \u062f\u0641\u0646 \u067e\u0633\u0645\u0627\u0646\u062f\u0647\u0627\u06cc \u063a\u0630\u0627\u06cc\u06cc \u0648 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0638\u0631\u0648\u0641 \u062a\u062c\u0632\u06cc\u0647\u200c\u067e\u0630\u06cc\u0631 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0627\u0632 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a \u062d\u0641\u0627\u0638\u062a \u06a9\u0631\u062f.<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-3\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \">\u0628\u0647\u062a\u0631\u06cc\u0646 \u0648 \u0645\u0647\u0645\u062a\u0631\u06cc\u0646 \u0631\u0627\u0647 \u0628\u0631\u0627\u06cc \u062d\u0641\u0627\u0638\u062a \u0627\u0632 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a \u0686\u06cc\u0633\u062a\u061f<\/h3>\n<div class=\"rank-math-answer \">\n\n<p>\u0628\u0647\u062a\u0631\u06cc\u0646 \u0648 \u0645\u0647\u0645\u200c\u062a\u0631\u06cc\u0646 \u0631\u0627\u0647 \u0628\u0631\u0627\u06cc \u062d\u0641\u0627\u0638\u062a \u0627\u0632 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a \u0627\u06cc\u0646 \u0627\u0633\u062a \u06a9\u0647 \u062f\u0631\u0627\u06cc\u0646\u200c\u0628\u0627\u0631\u0647 \u0628\u0627 \u0645\u0637\u0627\u0644\u0639\u0647 \u06a9\u0627\u0641\u06cc\u060c \u0622\u06af\u0627\u0647 \u0634\u0648\u06cc\u0645 \u0648 \u0628\u0639\u062f \u0628\u0647 \u0627\u0646\u062f\u0627\u0632\u0647 \u062a\u0648\u0627\u0646 \u0648 \u0627\u0645\u06a9\u0627\u0646\u0627\u062a\u0645\u0627\u0646\u060c \u062f\u0631 \u0627\u06cc\u0646 \u062c\u0647\u062a \u0642\u062f\u0645 \u0628\u0631\u062f\u0627\u0631\u06cc\u0645.<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-4\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \">\u0686\u06af\u0648\u0646\u0647 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a \u0631\u0627 \u067e\u0627\u06a9\u06cc\u0632\u0647 \u0646\u06af\u0647 \u062f\u0627\u0631\u06cc\u0645\u061f<\/h3>\n<div class=\"rank-math-answer \">\n\n<p>\u0632\u0628\u0627\u0644\u0647 \u062e\u0648\u062f \u0631\u0627 \u062f\u0631 \u0637\u0628\u06cc\u0639\u062a \u0631\u0647\u0627 \u0646\u06a9\u0646\u06cc\u0645\u060c \u0627\u0632 \u0648\u0633\u0627\u06cc\u0644 \u062d\u0645\u0644\u200c\u0648\u0646\u0642\u0644 \u0639\u0645\u0648\u0645\u06cc \u0628\u0631\u0627\u06cc \u0631\u0641\u062a\u200c\u0648\u0622\u0645\u062f\u0645\u0627\u0646 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u0645 \u0648 \u062f\u0631 \u0645\u0635\u0631\u0641 \u0622\u0628\u060c \u0628\u0631\u0642 \u0648... \u0635\u0631\u0641\u0647\u200c\u062c\u0648\u06cc\u06cc \u06a9\u0646\u06cc\u0645.<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-5\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \">\u0686\u0647 \u0628\u0627\u06cc\u062f \u06a9\u0631\u062f \u062a\u0627 \u0637\u0628\u06cc\u0639\u062a \u0632\u06cc\u0628\u0627\u06cc \u0645\u0627 \u062f\u0686\u0627\u0631 \u0622\u0644\u0648\u062f\u06af\u06cc \u0646\u0634\u0648\u062f\u061f<\/h3>\n<div class=\"rank-math-answer \">\n\n<p>\u062f\u0631 \u0647\u0646\u06af\u0627\u0645 \u062e\u0631\u06cc\u062f \u0627\u0632 \u06a9\u06cc\u0633\u0647\u200c\u0647\u0627\u06cc \u067e\u0627\u0631\u0686\u0647\u200c\u0627\u06cc \u0628\u0647 \u062c\u0627\u06cc \u067e\u0644\u0627\u0633\u062a\u06cc\u06a9\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u06a9\u0646\u06cc\u0645 \u0648 \u0632\u0628\u0627\u0644\u0647 \u062e\u0648\u062f \u0631\u0627 \u062f\u0631 \u0637\u0628\u06cc\u0639\u062a \u0631\u0647\u0627 \u0646\u06a9\u0646\u06cc\u0645. \u0645\u0646\u0627\u0628\u0639 \u0622\u0628\u06cc \u0645\u0627\u0646\u0646\u062f \u0631\u0648\u062f\u062e\u0627\u0646\u0647\u200c\u0647\u0627 \u0631\u0627 \u0628\u0627 \u0645\u0648\u0627\u062f \u0634\u0648\u06cc\u0646\u062f\u0647 \u0622\u0644\u0648\u062f\u0647 \u0646\u06a9\u0646\u06cc\u0645 \u0648 \u0647\u0646\u06af\u0627\u0645 \u062d\u0636\u0648\u0631 \u062f\u0631 \u0637\u0628\u06cc\u0639\u062a\u060c \u0633\u06a9\u0648\u062a \u0631\u0627 \u0631\u0639\u0627\u06cc\u062a \u06a9\u0646\u06cc\u0645.<\/p>\n\n<\/div>\n<\/div>\n<div id=\"faq-6\" class=\"rank-math-list-item\">\n<h3 class=\"rank-math-question \">\u0628\u0647\u062a\u0631\u06cc\u0646 \u0631\u0627\u0647 \u062d\u0641\u0627\u0638\u062a \u0627\u0632 \u0637\u0628\u06cc\u0639\u062a \u062f\u0631 \u0645\u0642\u0627\u0628\u0644 \u06af\u0631\u062f\u0634\u06af\u0631\u0627\u0646 \u0686\u06cc\u0633\u062a\u061f<\/h3>\n<div class=\"rank-math-answer \">\n\n<p>\u0622\u06af\u0627\u0647\u200c\u06a9\u0631\u062f\u0646 \u06af\u0631\u062f\u0634\u06af\u0631\u0627\u0646 \u062f\u0631\u0628\u0627\u0631\u0647 \u0627\u0642\u0627\u0645\u062a \u062f\u0631 \u0647\u062a\u0644\u200c\u0647\u0627\u06cc \u0633\u0628\u0632\u060c \u0628\u0631\u067e\u0627\u0646\u06a9\u0631\u062f\u0646 \u0622\u062a\u0634 \u062f\u0631 \u0637\u0628\u06cc\u0639\u062a \u0648 \u0628\u06cc\u0631\u0648\u0646 \u0646\u06cc\u0627\u0646\u062f\u0627\u062e\u062a\u0646 \u0632\u0628\u0627\u0644\u0647.<\/p>\n\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div><\/p>\n\n\n<div class=\"kk-star-ratings kksr-auto kksr-align-center kksr-valign-bottom\"\n    data-payload='{&quot;align&quot;:&quot;center&quot;,&quot;id&quot;:&quot;14097&quot;,&quot;slug&quot;:&quot;default&quot;,&quot;valign&quot;:&quot;bottom&quot;,&quot;ignore&quot;:&quot;&quot;,&quot;reference&quot;:&quot;auto&quot;,&quot;class&quot;:&quot;&quot;,&quot;count&quot;:&quot;1995&quot;,&quot;legendonly&quot;:&quot;&quot;,&quot;readonly&quot;:&quot;&quot;,&quot;score&quot;:&quot;3.1&quot;,&quot;starsonly&quot;:&quot;&quot;,&quot;best&quot;:&quot;5&quot;,&quot;gap&quot;:&quot;4&quot;,&quot;greet&quot;:&quot;\u0644\u0637\u0641\u0627 \u0628\u0647 \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647 \u0627\u0645\u062a\u06cc\u0627\u0632 \u062f\u0647\u06cc\u062f&quot;,&quot;legend&quot;:&quot;3.1\\\/5 - (1995 \u0627\u0645\u062a\u06cc\u0627\u0632)&quot;,&quot;size&quot;:&quot;30&quot;,&quot;title&quot;:&quot;20+ \u0631\u0648\u0634 \u062d\u0641\u0627\u0638\u062a \u0627\u0632 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a \u0648 \u0627\u062d\u062a\u0631\u0627\u0645 \u0628\u0647 \u0637\u0628\u06cc\u0639\u062a \u062f\u0631 \u0633\u0641\u0631&quot;,&quot;width&quot;:&quot;103.4&quot;,&quot;_legend&quot;:&quot;{score}\\\/{best} - ({count} {votes})&quot;,&quot;font_factor&quot;:&quot;1.25&quot;}'>\n            \n<div class=\"kksr-stars\">\n    \n<div class=\"kksr-stars-inactive\">\n            <div class=\"kksr-star\" data-star=\"1\" style=\"padding-left: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 30px; height: 30px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"2\" style=\"padding-left: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 30px; height: 30px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"3\" style=\"padding-left: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 30px; height: 30px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"4\" style=\"padding-left: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 30px; height: 30px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" data-star=\"5\" style=\"padding-left: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 30px; height: 30px;\"><\/div>\n        <\/div>\n    <\/div>\n    \n<div class=\"kksr-stars-active\" style=\"width: 103.4px;\">\n            <div class=\"kksr-star\" style=\"padding-left: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 30px; height: 30px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-left: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 30px; height: 30px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-left: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 30px; height: 30px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-left: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 30px; height: 30px;\"><\/div>\n        <\/div>\n            <div class=\"kksr-star\" style=\"padding-left: 4px\">\n            \n\n<div class=\"kksr-icon\" style=\"width: 30px; height: 30px;\"><\/div>\n        <\/div>\n    <\/div>\n<\/div>\n                \n\n<div class=\"kksr-legend\" style=\"font-size: 24px;\">\n            \u06f3.\u06f1\/\u06f5 - (\u06f1\u06f9\u06f9\u06f5 \u0627\u0645\u062a\u06cc\u0627\u0632)    <\/div>\n    <\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u0647\u0631 \u0633\u0627\u0644 \u0647\u0632\u0627\u0631\u0627\u0646\u200c\u0647\u0632\u0627\u0631 \u06af\u0648\u0646\u0647 \u06af\u06cc\u0627\u0647\u06cc \u0648 \u062c\u0627\u0646\u0648\u0631\u06cc \u0646\u0627\u0628\u0648\u062f \u0645\u06cc\u200c\u0634\u0648\u0646\u062f \u0648 \u062a\u0639\u062f\u0627\u062f \u0632\u06cc\u0627\u062f\u06cc \u0627\u0632 \u0645\u0648\u062c\u0648\u062f\u0627\u062a \u0622\u0628\u0632\u06cc \u062f\u0631 \u0627\u062b\u0631 \u0622\u0644\u0648\u062f\u06af\u06cc \u0622\u0628\u200c\u0647\u0627 \u0645\u06cc\u200c\u0645\u06cc\u0631\u0646\u062f! \u0627\u06cc\u0646 \u0622\u0645\u0627\u0631\u0647\u0627 \u0648\u0627\u0642\u0639\u0627 \u063a\u0645\u200c\u0627\u0646\u06af\u06cc\u0632 \u0627\u0633\u062a! \u0628\u0647 \u062e\u0635\u0648\u0635 \u0648\u0642\u062a\u06cc \u0645\u06cc\u200c\u0641\u0647\u0645\u06cc\u0645 \u06a9\u0647 \u0639\u0627\u0645\u0644 \u0627\u06cc\u0646 \u0647\u0645\u0647 \u0622\u0633\u06cc\u0628 \u0648 \u0646\u0627\u0628\u0648\u062f\u06cc \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a\u060c \u062e\u0648\u062f\u062e\u0648\u0627\u0647\u06cc \u0648 \u0641\u0639\u0627\u0644\u06cc\u062a\u200c\u0647\u0627\u06cc \u0645\u062e\u0631\u0628 \u0627\u0646\u0633\u0627\u0646 \u0627\u0633\u062a. \u0628\u0627 \u0648\u062c\u0648\u062f \u0627\u06cc\u0646 \u0622\u0645\u0627\u0631\u0647\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 \u0645\u062d\u06cc\u0637 \u0632\u06cc\u0633\u062a \u0627\u06cc\u0631\u0627\u0646 \u0648 \u062d\u0641\u0627\u0638\u062a [&hellip;]<\/p>\n","protected":false},"author":69,"featured_media":37868,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2538,2615],"tags":[],"class_list":["post-14097","post","type-post","status-publish","format-standard","has-post-thumbnail","","category-2538","category-iran"],"_links":{"self":[{"href":"https:\/\/www.eghamat24.com\/blog\/wp-json\/wp\/v2\/posts\/14097","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eghamat24.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eghamat24.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eghamat24.com\/blog\/wp-json\/wp\/v2\/users\/69"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eghamat24.com\/blog\/wp-json\/wp\/v2\/comments?post=14097"}],"version-history":[{"count":0,"href":"https:\/\/www.eghamat24.com\/blog\/wp-json\/wp\/v2\/posts\/14097\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eghamat24.com\/blog\/wp-json\/wp\/v2\/media\/37868"}],"wp:attachment":[{"href":"https:\/\/www.eghamat24.com\/blog\/wp-json\/wp\/v2\/media?parent=14097"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eghamat24.com\/blog\/wp-json\/wp\/v2\/categories?post=14097"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eghamat24.com\/blog\/wp-json\/wp\/v2\/tags?post=14097"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}